{"id":28445,"date":"2020-05-22T20:39:57","date_gmt":"2020-05-22T20:39:57","guid":{"rendered":"https:\/\/sertv.gob.pa\/crisolfm\/?p=28445"},"modified":"2020-05-22T20:39:57","modified_gmt":"2020-05-22T20:39:57","slug":"atp-y-cnt-alinean-objetivos-para-desarrollar-plan-maestro-de-turismo","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/crisolfm\/atp-y-cnt-alinean-objetivos-para-desarrollar-plan-maestro-de-turismo\/","title":{"rendered":"ATP y CNT alinean objetivos para desarrollar plan maestro de turismo"},"content":{"rendered":"<p>Los nuevos miembros de la Junta Directiva del Consejo Nacional de Turismo (CNT) sostuvieron su primera reuni\u00f3n con el ministro de Turismo, Iv\u00e1n Eskildsen, quien les present\u00f3 los avances de la actualizaci\u00f3n del Plan Maestro de Turismo Sostenible (PMTS) 2007-2020, el cual a la fecha registra un avance de 50%.<\/p>\n<p>El presidente del CNT, Jorge Garc\u00eda Icaza, expres\u00f3 que se le dar\u00e1 seguimiento a la implementaci\u00f3n del PMTS y al uso eficiente del recurso que se le asigne a la ATP en el presupuesto general de la naci\u00f3n.<\/p>\n<p>Garc\u00eda Icaza\u00a0destac\u00f3\u00a0que \u00abla industria tur\u00edstica ser\u00e1 una de las m\u00e1s golpeadas por la pandemia y demorar\u00e1 varios a\u00f1os en recuperarse\u00bb. Enfatiz\u00f3 la importancia de que el turismo cuente con una visi\u00f3n compartida y consistente\u00a0de posicionamiento de marca pa\u00eds y un acuerdo nacional a seguir en los \u00faltimos a\u00f1os.<\/p>\n<p>Dijo sentirse optimista para trabajar con una industria unificada bajo el liderazgo del Administrador de la ATP y en alianza con el Fondo de Promoci\u00f3n Tur\u00edstica Internacional (PROMTUR), para enfrentar la dif\u00edcil situaci\u00f3n actual.<\/p>\n<p>El empresario resalt\u00f3 el trabajo que ha realizado la ATP, bajo la gesti\u00f3n del ministro Iv\u00e1n Eskildsen, en coordinaci\u00f3n con el Gabinete Tur\u00edstico, en asegurar que el pa\u00eds\u00a0y en particular los ocho polos tur\u00edsticos (Bocas del Toro, Boquete y Tierras Altas,\u00a0Santa Catalina, Pedas\u00ed, Riviera Pac\u00edfica, Ciudad de Panam\u00e1, Taboga y Portobelo), se conviertan en productos tur\u00edsticos de clase mundial.<\/p>\n<p>Destac\u00f3 que es importante que en estos ocho destinos cuenten con seguridad ciudadana, correcta disposici\u00f3n de la basura y servicios b\u00e1sicos; as\u00ed como brindar capacitaci\u00f3n a los emprendedores, quienes son los que crean productos tur\u00edsticos de la mano con la empresa privada.<\/p>\n<p>Eskildsen resalt\u00f3 que con las nuevas designaciones en el CNT se logra un balance entre experiencia y juventud y una representaci\u00f3n justa de todos los sectores del pa\u00eds. \u201cTodos cuentan con una amplia trayectoria reconocida dentro de la industria y comprometidos con el pa\u00eds\u201d, puntualiz\u00f3.<\/p>\n<p>El CNT, como m\u00e1ximo \u00f3rgano de direcci\u00f3n y consulta en materia tur\u00edstica en la Rep\u00fablica de Panam\u00e1, tiene la responsabilidad de aprobar el PMTS, el cual\u00a0se actualizar\u00e1 hasta el 2025 y el presupuesto de la ATP, entre otras funciones de relevancia.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente:\u00a0\u00a0 ATP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los nuevos miembros de la Junta Directiva del Consejo Nacional <a href=\"https:\/\/sertv.gob.pa\/crisolfm\/atp-y-cnt-alinean-objetivos-para-desarrollar-plan-maestro-de-turismo\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":64,"featured_media":28446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-28445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varios"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/28445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/comments?post=28445"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/28445\/revisions"}],"predecessor-version":[{"id":28447,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/28445\/revisions\/28447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media\/28446"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media?parent=28445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/categories?post=28445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/tags?post=28445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}