{"id":3242,"date":"2015-09-22T16:08:34","date_gmt":"2015-09-22T16:08:34","guid":{"rendered":""},"modified":"2015-09-22T16:08:34","modified_gmt":"2015-09-22T16:08:34","slug":"dos-mil-plantones-seran-sembrados-en-azuero","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/crisolfm\/dos-mil-plantones-seran-sembrados-en-azuero\/","title":{"rendered":"Dos mil plantones ser\u00e1n sembrados en Azuero"},"content":{"rendered":"<p>\nVoluntarios y activistas sembrar\u00e1n 2 mil plantones como parte de la actividad &lsquo;Reforestemos Azuero&#8217;, \u00a0el pr\u00f3ximo 25 de septiembre <\/p>\n<p>La jornada tiene como prop\u00f3sito preservar el caudal h\u00eddrico del \u00e1rea de Azuero y conservar el medio ambiente, como parte de la promesa de la Media Marat\u00f3n Hacienda San Isidro, de sembrar un \u00e1rbol por cada corredor que cruz\u00f3 la meta, este a\u00f1o. <\/p>\n<p>Para ello, se tiene previsto el apoyo de 200 personas de organizaciones y agrupaciones juveniles como Azuero Earth Project, Asociaci\u00f3n Panam\u00e1 Verde, Servicios Agr\u00edcolas, S.A. voluntarios de Varela Hermanos, estudiantes de la escuela de Las Cabras de Pes\u00e9, Escuela Hildaura Vieto, Colegio Jos\u00e9 Octavio Huertas y 22 participantes del concurso Miss Latinoam\u00e9rica 2015. <\/p>\n<p>La actividad se llevar\u00e1 a cabo en un terrero de ocho hect\u00e1reas, de Varela Hermanos, S.A., en Pes\u00e9. <\/p>\n<p>\u00a0 <\/p>\n<p>\u00a0 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voluntarios y activistas sembrar\u00e1n 2 mil plantones como parte de <a href=\"https:\/\/sertv.gob.pa\/crisolfm\/dos-mil-plantones-seran-sembrados-en-azuero\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":3243,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-3242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecologicas"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/3242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/comments?post=3242"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/3242\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media\/3243"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media?parent=3242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/categories?post=3242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/tags?post=3242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}