{"id":54554,"date":"2022-08-16T21:13:18","date_gmt":"2022-08-16T21:13:18","guid":{"rendered":"https:\/\/sertv.gob.pa\/crisolfm\/?p=54554"},"modified":"2022-08-16T21:13:18","modified_gmt":"2022-08-16T21:13:18","slug":"acodeco-verifica-rebaja-del-30-de-los-170-medicamentos","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/crisolfm\/acodeco-verifica-rebaja-del-30-de-los-170-medicamentos\/","title":{"rendered":"ACODECO verifica rebaja del 30% de los 170 medicamentos"},"content":{"rendered":"<p><strong><em>En cumplimiento del Decreto Ejecutivo No. 17 de 10 de agosto de 2022, que disminuye en un 30% el precio de 170 medicamentos por seis meses prorrogables, la Autoridad de Protecci\u00f3n al Consumidor y Defensa de la Competencia (ACODECO) inici\u00f3 las respectivas verificaciones desde ayer 15 de agosto de 2022, en todo el pa\u00eds.<\/em><\/strong><\/p>\n<p>Las acciones de la ACODECO, se han concentrado en aquellos locales que se mantienen abiertos al p\u00fablico, con el fin de verificar la aplicaci\u00f3n del descuento respectivo.\u00a0Durante un recorrido este martes 16 de agosto, se visitaron las siguientes farmacias en ciudad capital: Riba Smith, Saba, Farma Value, Super 99, El Rey calle 50 y Xtra. Todas estas, cumpl\u00edan con otorgar el descuento del 30% y adicional el 20% a los jubilados como lo establece el decreto ejecutivo N\u00b0 17 del 10 de agosto de 2000. Solo en Farmacia Arrocha de calle 50, se levant\u00f3 acta por no cumplir con el descuento del 30% en un medicamento que manten\u00eda a\u00a0la venta.<\/p>\n<p>Cabe destacar, que la ACODECO, es la instituci\u00f3n encargada de aplicar las medidas necesarias para implementar y verificar el cumplimiento de lo dispuestos en este decreto ejecutivo.<\/p>\n<p><strong><em>La lista completa de los 170 productos medicinales rebajados, puede\u00a0ser consultados a trav\u00e9s del Sistema de Informaci\u00f3n y Denuncia Institucional (Sindi), WhatsApp y Telegram 6330-3333, las cuentas de las redes sociales AcodecoPma en Facebook, Twitter y la p\u00e1gina web de esta instituci\u00f3n. Asimismo, cualquier denuncia al respecto se puede hacer por este medio.<\/em><\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p>Fuente: ACODECO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cumplimiento del Decreto Ejecutivo No. 17 de 10 de <a href=\"https:\/\/sertv.gob.pa\/crisolfm\/acodeco-verifica-rebaja-del-30-de-los-170-medicamentos\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":53329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-54554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varios"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/comments?post=54554"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54554\/revisions"}],"predecessor-version":[{"id":54557,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54554\/revisions\/54557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media\/53329"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media?parent=54554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/categories?post=54554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/tags?post=54554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}