{"id":54585,"date":"2022-08-17T19:53:32","date_gmt":"2022-08-17T19:53:32","guid":{"rendered":"https:\/\/sertv.gob.pa\/crisolfm\/?p=54585"},"modified":"2022-08-17T19:53:32","modified_gmt":"2022-08-17T19:53:32","slug":"ingresos-corrientes-acumulados-del-estado-a-julio-se-ubican-en-b-3806-9-millones","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/crisolfm\/ingresos-corrientes-acumulados-del-estado-a-julio-se-ubican-en-b-3806-9-millones\/","title":{"rendered":"Ingresos corrientes acumulados del Estado a julio se ubican en B\/. 3,806.9 millones"},"content":{"rendered":"<p>Al cierre de julio de 2022, los ingresos corrientes acumulados del Estado totalizaron B\/. 3,806.9 millones, reflejando un aumento de B\/. 536.2 millones versus al a\u00f1o anterior, detalla el Informe Preliminar de Recaudaci\u00f3n de la Direcci\u00f3n General de Ingresos (DGI) del Ministerio de Econom\u00eda y Finanzas de Panam\u00e1 (MEF).<\/p>\n<p>Por su parte, la recaudaci\u00f3n de los Ingresos Tributarios acumulados a julio 2022, se ubicaron en B\/. 3,033 millones, \u00e9stos reflejan un d\u00e9ficit de B\/. 82.6 millones en comparaci\u00f3n al presupuesto, sin embargo, sobrepasaron en B\/. 595.1 millones la recaudaci\u00f3n del a\u00f1o anterior, indica el documento de la DGI.<\/p>\n<p>De acuerdo al comportamiento de los Impuestos Directos e Indirectos comparado con el mismo periodo del a\u00f1o anterior; los que muestran mayores incrementos son: Persona Jur\u00eddica con B\/. 195.5 millones, Complementario con B\/. 26.9 millones, Inmuebles con B\/. 23.9 millones, Dividendos con B\/. 22.5 millones, Ganancia de Capital Valores con B\/. 30.5 millones y Ganancia de Capital Inmuebles con B\/.11.0 millones.<\/p>\n<p>En comparaci\u00f3n a la meta presupuestada sin Documentos Fiscales, la recaudaci\u00f3n de los Ingresos Tributarios al cierre de julio de 2022, refleja un d\u00e9ficit\u00a0\u00a0 aproximado de 2.7% en donde los Impuestos Directos reflejan: B\/. 80.1 millones, con 4.8% m\u00e1s y los Indirectos\u00a0B\/. 162.7 millones, 11.3%\u00a0por abajo de lo presupuestado.<\/p>\n<p>Mientras que, los Ingresos no Tributarios acumulados a julio 2022 alcanzaron la suma de B\/. 723.7 millones, representando lo recaudado en tasas, derechos y otros un 80% del total acumulado al mes de julio.<\/p>\n<p>En cuanto a lo esperado en el art\u00edculo presupuesto ley acumulado a julio 2022, el comportamiento en la participaci\u00f3n de utilidades y aportes, reflej\u00f3 un super\u00e1vit de 17.9%.<\/p>\n<p>Para el mes de julio 2022, los Ingresos Corrientes reflejaron un total de B\/. 462.7 millones. De ese total, B\/. 343 millones, pertenecen a la recaudaci\u00f3n de Ingresos Tributarios, B\/. 88.1 millones a ingresos no tributarios y B\/. 31.6 millones a otros Ingresos Corrientes, refleja el\u00a0informe de la DGI.<\/p>\n<p><a href=\"https:\/\/dgi.mef.gob.pa\/_4Transparencia\/IFP\/IPR2022-Jul.pdf\" target=\"_blank\" rel=\"noopener\"><strong>https:\/\/dgi.mef.gob.pa\/_4Transparencia\/IFP\/IPR2022-Jul.pdf<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: MEF<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al cierre de julio de 2022, los ingresos corrientes acumulados <a href=\"https:\/\/sertv.gob.pa\/crisolfm\/ingresos-corrientes-acumulados-del-estado-a-julio-se-ubican-en-b-3806-9-millones\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":54586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-54585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varios"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/comments?post=54585"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54585\/revisions"}],"predecessor-version":[{"id":54587,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54585\/revisions\/54587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media\/54586"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media?parent=54585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/categories?post=54585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/tags?post=54585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}