{"id":54598,"date":"2022-08-17T20:56:09","date_gmt":"2022-08-17T20:56:09","guid":{"rendered":"https:\/\/sertv.gob.pa\/crisolfm\/?p=54598"},"modified":"2022-08-17T20:56:09","modified_gmt":"2022-08-17T20:56:09","slug":"abastecimiento-de-medicamentos-en-centros-y-policentros-de-salud-de-todo-el-pais-se-mantendra-ministro-sucre","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/crisolfm\/abastecimiento-de-medicamentos-en-centros-y-policentros-de-salud-de-todo-el-pais-se-mantendra-ministro-sucre\/","title":{"rendered":"Abastecimiento de medicamentos en centros y policentros de Salud de todo el pa\u00eds se mantendr\u00e1: Ministro Sucre"},"content":{"rendered":"<p>El ministro de Salud de Panam\u00e1, Luis Francisco Sucre, en reuni\u00f3n sostenida con el equipo de directores nacionales y regionales, dispuso que, se mantenga el abastecimiento de todos los medicamentos a los centros, subcentros y policentros de Salud, en todo el territorio nacional.<\/p>\n<p>Destac\u00f3 Sucre, que las farmacias del Ministerio de Salud (MINSA), deben tener disponibles antibi\u00f3ticos, medicinas para la presi\u00f3n arterial, sueros orales, medicamentos para la salud mental y lo que tengan mayor demanda en la poblaci\u00f3n, para as\u00ed garantizar en todo momento, los medicamentos a la ciudadan\u00eda.<\/p>\n<p>Para el Ministerio de Salud (MINSA), es primordial mantener a disposici\u00f3n de la poblaci\u00f3n, los productos del cuadro de medicamentos para que sigan recibiendo, sin mayor contratiempo, sus medicinas y as\u00ed garantizar su bienestar y una mejor calidad de vida.<\/p>\n<p>El titular de Salud, agreg\u00f3 que esta medida no es un paliativo, ya que las farmacias de los centros de Salud se est\u00e1n reforzando constantemente y brindan medicamentos de calidad y a un bajo costo, tanto a la poblaci\u00f3n no asegurada como asegurada.<\/p>\n<p>El Gobierno Nacional a trav\u00e9s del MINSA sigue comprometido en mantener el abastecimiento de medicamentos ante la postura de algunos establecimientos farmac\u00e9uticos de no abrir sus puertas ante la entrada del Decreto 17, mientras que se les recuerda a las farmacias que deben mantener la cadena de frio, adem\u00e1s de cumplir con las buenas pr\u00e1cticas de manufactura, almacenamiento, transporte y dispensaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente : MINSA<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Salud de Panam\u00e1, Luis Francisco Sucre, en <a href=\"https:\/\/sertv.gob.pa\/crisolfm\/abastecimiento-de-medicamentos-en-centros-y-policentros-de-salud-de-todo-el-pais-se-mantendra-ministro-sucre\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":54599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-54598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varios"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/comments?post=54598"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54598\/revisions"}],"predecessor-version":[{"id":54601,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54598\/revisions\/54601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media\/54599"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media?parent=54598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/categories?post=54598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/tags?post=54598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}