{"id":54789,"date":"2022-08-24T21:12:29","date_gmt":"2022-08-24T21:12:29","guid":{"rendered":"https:\/\/sertv.gob.pa\/crisolfm\/?p=54789"},"modified":"2022-08-24T21:12:29","modified_gmt":"2022-08-24T21:12:29","slug":"en-herrera-acodeco-destruyo-mas-de-1500-productos","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/crisolfm\/en-herrera-acodeco-destruyo-mas-de-1500-productos\/","title":{"rendered":"En Herrera, ACODECO, destruy\u00f3 m\u00e1s de 1,500 productos"},"content":{"rendered":"<p><strong><em>Decomisados en casi 2 meses<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>La Autoridad de Protecci\u00f3n al Consumidor y Defensa de la Competencia (ACODECO) en la provincia de Herrera,\u00a0destruy\u00f3 hoy, en el vertedero de Chitr\u00e9, 1,577\u00a0productos que fueron retirados de la venta, durante verificaciones a 69 establecimientos comerciales.\u200b\u00a0<\/strong><\/p>\n<p>Estos productos corresponden a las acciones desarrolladas desde el 1 de julio al 23 de agosto del presente a\u00f1o.\u00a0 Fueron decomisados 1,411 productos expirados, 73 deteriorados, 77 sin fecha de vencimiento a la vista y 16 que no ten\u00edan esa fecha en forma clara.\u00a0 Adem\u00e1s, en este per\u00edodo se detectaron 38 faltas de precios visibles.<\/p>\n<p>Entre los productos decomisados se encuentran:\u00a0 embutidos, menestras, paquetes de pa\u00f1ales, champ\u00fas, tintes para cabello, enlatados, arroz, sobres\u00a0de sopa,\u00a0gaseosas,\u00a0detergentes, yogures, desodorantes, jugos, galletas, paquetes de pan cake, l\u00edquidos para zapatos, latas de pintura en espray y snacks, entre\u00a0otros.\u00a0\u00a0Estos productos\u00a0 \u00a0fueron retirados\u00a0en locales comerciales ubicados en los distritos\u00a0de Oc\u00fa, Los Pozos, Chitr\u00e9, Las Minas y Pes\u00e9.<\/p>\n<p>Cabe destacar que, en Herrera, desde enero al 23 de agosto de 2022, se decomisaron 7,333<strong>\u00a0productos y se verificaron 542\u00a0<\/strong>agentes econ\u00f3micos (minis\u00faper, abarroter\u00edas, supermercados, kioscos, restaurantes y fondas, entre otros).<\/p>\n<p><strong>A nivel nacional, de enero a julio de 2022, la ACODECO, ha decomisado 51.406 productos vencidos; 1,036 sin fecha de vencimiento y 219 que no ten\u00edan esa fecha clara, y 1,115 alimentos deteriorados.\u00a0<\/strong><\/p>\n<p>Al visualizar la fecha de caducidad de un producto, es importante tener en cuenta que esta hace referencia o indica la fecha tope la cual es recomendable consumir el mismo. Luego de dicha fecha, el producto se vuelve potencialmente nocivo.<\/p>\n<p>La ACODECO, mantiene una constante fiscalizaci\u00f3n para garantizar el cumplimiento de las normas de protecci\u00f3n al consumidor.\u00a0 Se les recuerda a los consumidores, que cualquier denuncia o queja, pueden presentarla a trav\u00e9s del asistente virtual Sindi, mediante el WhatsApp y Telegram 6330-3333, las cuentas de las redes sociales AcodecoPma en Facebook, Twitter, y la p\u00e1gina web.\u00a0 Las denuncias son an\u00f3nimas, pero deben describir las faltas, el nombre y ubicaci\u00f3n exacta del establecimiento comercial.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: ACODECO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decomisados en casi 2 meses &nbsp; La Autoridad de Protecci\u00f3n <a href=\"https:\/\/sertv.gob.pa\/crisolfm\/en-herrera-acodeco-destruyo-mas-de-1500-productos\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":54790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-54789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varios"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/comments?post=54789"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54789\/revisions"}],"predecessor-version":[{"id":54792,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/54789\/revisions\/54792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media\/54790"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media?parent=54789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/categories?post=54789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/tags?post=54789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}