{"id":8781,"date":"2017-07-24T16:18:58","date_gmt":"2017-07-24T16:18:58","guid":{"rendered":""},"modified":"2017-07-24T16:18:58","modified_gmt":"2017-07-24T16:18:58","slug":"estudiantes-viajan-a-japon-y-nos-representan-en-robocup","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/crisolfm\/estudiantes-viajan-a-japon-y-nos-representan-en-robocup\/","title":{"rendered":"Estudiantes viajan a Jap\u00f3n y nos representan en \u201cRoboCup\u201d"},"content":{"rendered":"<p>\nUn grupo de 6 j\u00f3venes paname\u00f1os, estudiantes del Colegio San Vicente de Pa\u00fal (Veraguas) y el Instituto Episcopal San Jos\u00e9 (Panam\u00e1 Oeste), representar\u00e1n al pa\u00eds en la competencia internacional de rob\u00f3tica m\u00e1s importante del mundo: &ldquo;RoboCup&rdquo;, que promueve la investigaci\u00f3n en rob\u00f3tica y la inteligencia artificial. <\/p>\n<p>La XXI edici\u00f3n de este torneo se efectuar\u00e1 del 27 al 31 de julio de 2017 en Nagoya, Jap\u00f3n, y reunir\u00e1 a miles de &lsquo;RoboCuppers&#8217; de todas partes del mundo para demostrar sus conocimientos en programaci\u00f3n, electr\u00f3nica, ingenier\u00eda y rob\u00f3tica. <\/p>\n<p>Los 6 j\u00f3venes que representar\u00e1n a Panam\u00e1 fueron los ganadores de la Competencia RoboCupJunior Panam\u00e1 2017, organizado por la Secretar\u00eda Nacional de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n (SENACYT), el Ministerio de Educaci\u00f3n (MEDUCA) y el Comit\u00e9 Nacional de Rob\u00f3tica y Aplicaciones Inform\u00e1ticas, con el prop\u00f3sito de motivar a la juventud a aprender m\u00e1s sobre ciencia, tecnolog\u00eda, ingenier\u00eda y matem\u00e1ticas (STEM). <\/p>\n<p>Igualmente tiene como prop\u00f3sito fomentar las vocaciones tecnol\u00f3gicas mediante la difusi\u00f3n y el desarrollo de la rob\u00f3tica educativa en Panam\u00e1. <\/p>\n<p>La Gran Final de esta competencia de rob\u00f3tica reuni\u00f3 a un total de 42 equipos de distintos centros educativos a nivel nacional. <\/p>\n<p>\u00a0 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de 6 j\u00f3venes paname\u00f1os, estudiantes del Colegio San <a href=\"https:\/\/sertv.gob.pa\/crisolfm\/estudiantes-viajan-a-japon-y-nos-representan-en-robocup\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":8782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-8781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varios"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/8781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/comments?post=8781"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/posts\/8781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media\/8782"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/media?parent=8781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/categories?post=8781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/crisolfm\/wp-json\/wp\/v2\/tags?post=8781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}