{"id":101872,"date":"2024-11-29T08:41:18","date_gmt":"2024-11-29T13:41:18","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=101872"},"modified":"2024-11-29T08:41:18","modified_gmt":"2024-11-29T13:41:18","slug":"presidente-mulino-se-reune-con-productores-en-boquete-e-inspecciona-trabajos-de-reparacion-tras-recientes-lluvias","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/presidente-mulino-se-reune-con-productores-en-boquete-e-inspecciona-trabajos-de-reparacion-tras-recientes-lluvias\/","title":{"rendered":"Presidente Mulino se re\u00fane con productores en Boquete e inspecciona trabajos de reparaci\u00f3n, tras recientes lluvias"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-content-alignment:justify;\"><p>El presidente de la Rep\u00fablica de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, se reuni\u00f3 hace poco, con productores en Boquete, provincia de Chiriqu\u00ed, para evaluar, entre otros temas, las afectaciones que ha sufrido el agro por las fuertes lluvias provocadas recientemente por la tormenta Rafael, que tambi\u00e9n causaron inundaciones y cobraron vidas en otros puntos del pa\u00eds.<\/p>\n<p>Ganaderos, cafetaleros y horticultores, entre otros representantes del agro en la regi\u00f3n, estuvieron en el encuentro, donde el presidente Mulino, envi\u00f3 un mensaje a este importante sector de la econom\u00eda del pa\u00eds: \u201cCuenten con el Gobierno Nacional; el agro para m\u00ed es importante, m\u00e1s all\u00e1 de las estad\u00edsticas o del producto interno bruto; son chiquitos, pero c\u00f3mo dan empleos\u201d.<\/p>\n<p>A la vez, inst\u00f3 a los productores a que, con el titular del MIDA, tras las recientes afectaciones por las fuertes lluvias, se contin\u00fae realizando evaluaciones en las fincas para determinar la magnitud de los da\u00f1os y buscar los mecanismos para dar alternativas.<\/p>\n<p>Durante la reuni\u00f3n, los productores tambi\u00e9n abordaron con las autoridades gubernamentales aspectos relacionados a los financiamientos que otorga el Banco de Desarrollo Agropecuario (BDA), as\u00ed como sus inquietudes por la pr\u00f3xima entrada de Panam\u00e1 al Mercado Com\u00fan del Sur (Mercosur).<\/p>\n<p>Sobre esto \u00faltimo, el mandatario, explic\u00f3 que, el ingreso del pa\u00eds al Mercosur, previsto para la pr\u00f3xima semana, ser\u00e1 como \u201cEstado Asociado\u201d y no existe nada en la agenda, de momento, relacionado a un acuerdo o tratado de libre comercio con este bloque; y aunque eventualmente podr\u00eda ocurrir en el futuro, depender\u00eda de muchas cosas. \u201cPor lo pronto, estaremos en un mercado, un foro pol\u00edtico de mucho peso en el \u00e1mbito continental que le representar\u00e1 muchas oportunidades al pa\u00eds\u201d, dijo.<\/p>\n<p>Se\u00f1al\u00f3 que, para su administraci\u00f3n, el principal inter\u00e9s es la generaci\u00f3n de empleos, por eso se analizan las f\u00f3rmulas que pudieran aplicarse para que, en el interior del pa\u00eds, a trav\u00e9s del sector agropecuario, se puedan generar las oportunidades para que las nuevas generaciones se queden en la zona y no vayan hacia la congestionada ciudad capital.<\/p>\n<p>El jefe del Ejecutivo, anunci\u00f3 durante la reuni\u00f3n con los productores que pr\u00f3ximamente estar\u00e1 firmando el decreto de Gabinete que nombra el Gabinete Agropecuario, con representaci\u00f3n de los distintos sectores del pa\u00eds, con el \u00e1nimo de tener con los ministros, por lo menos, una reuni\u00f3n bimestral, \u201cpara poner los o\u00eddos en tierra\u201d. Tambi\u00e9n destac\u00f3, que el Gobierno, ha contemplado en el presupuesto para el pr\u00f3ximo a\u00f1o, el Proyecto de Riego de Boquete, para que m\u00e1s sembrad\u00edos se beneficien y se impulse la producci\u00f3n en la regi\u00f3n.<\/p>\n<p>El presidente Mulino, se\u00f1al\u00f3 a los productores, adem\u00e1s, que ha sostenido conversaciones con el gerente del Banco Nacional de Panam\u00e1 (BANCONAL), quien ha expresado en las sesiones del Consejo de Gabinete, que esta entidad bancaria est\u00e1 para apoyar al sector agropecuario, m\u00e1s a\u00fan por la emergencia provocada por las recientes precipitaciones.<\/p>\n<p>No obstante, indic\u00f3 que, el BANCONAL, al igual que los bancos privados, tiene que cumplir con las normativas vigentes como cualquier entidad crediticia. \u201cIncluso me han dicho: ac\u00e9rquense a nuestras agencias o sucursales y, si hay que restructurar, se restructura; si hay que dar t\u00e9rminos, se dan t\u00e9rminos para ayudar\u201d, dijo el mandatario, quien estuvo acompa\u00f1ado en el encuentro por los ministros Roberto Linares (MIDA) y Jos\u00e9 Luis Andrade (MOP) y la gobernadora de la provincia, Aixa Santamar\u00eda, entre otras autoridades.<\/p>\n<p>\u201cEl Gobierno paname\u00f1o, est\u00e1 cuadrado con el sector agropecuario, lo que necesitamos es este tipo de conversaciones francas, abiertas y sin protocolo alguno\u201d, expres\u00f3 el mandatario a los medios de comunicaci\u00f3n que dieron cobertura de la reuni\u00f3n.<\/p>\n<p>Por su parte, los productores manifestaron su satisfacci\u00f3n por el encuentro y la disponibilidad del Gobierno Nacional de escuchar las necesidades del sector, adem\u00e1s de mantener, a trav\u00e9s del MIDA, los acercamientos y coordinaciones para ayudarlos a reponerse de los estragos del fen\u00f3meno clim\u00e1tico, cuya cuant\u00eda de los da\u00f1os, indicaron, a\u00fan se est\u00e1 contabilizando, dado que poco a poco las lluvias comienzan a estabilizarse.<\/p>\n<p>\u201cLo m\u00e1s importante es que ya (las autoridades) est\u00e1n comenzando a realizar los trabajos de reparaci\u00f3n de v\u00edas que son importantes para transportar los productos de la cadena agroalimentaria. No necesitamos subsidios, solo las ayudas o financiamientos necesarios\u201d, indicaron al t\u00e9rmino de la cita.<\/p>\n<p><em><strong>Presidente inspecciona trabajos en la quebraza La Zumbona<\/strong><\/em><\/p>\n<p>Previo a la reuni\u00f3n con los productores, el presidente Mulino, junto a la gobernadora y los titulares del MIDA y del MOP, inspeccion\u00f3 el puente sobre la quebrada La Zumbona, en Boquete, que, tras las intensas lluvias en d\u00edas pasados, se desbord\u00f3 sobre terrenos y residencias, y que incluso ocasion\u00f3 da\u00f1os en la estructura del puente por la fuerza de la corriente.<\/p>\n<p>El MOP, en este momento ejecuta trabajos de dragado y canalizaci\u00f3n en el lugar para evitar nuevos desbordamientos.<\/p>\n<p>Estos trabajos, forman parte de las acciones que ha programado el Gobierno Nacional para recuperar las infraestructuras afectadas por las recientes lluvias, mientras se contin\u00faa atendiendo y dando respuestas a las familias que resultaron afectadas por las inundaciones.<\/p>\n<p>Fuente: Presidencia de la Rep\u00fablica de Panam\u00e1<\/p>\n<\/div><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\" style=\"--more-btn-alignment:center;\"><div style=\"margin:-5px;--awb-bordersize:0px;\" class=\"fusion-gallery fusion-gallery-container fusion-grid-3 fusion-columns-total-9 fusion-gallery-layout-grid fusion-gallery-1\"><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-2.jpeg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-2.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"MULINO Y PRODUCTORES 2\" aria-label=\"MULINO Y PRODUCTORES 2\" class=\"img-responsive wp-image-101874\" srcset=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-2-200x133.jpeg 200w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-2-400x267.jpeg 400w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-2.jpeg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-3.jpeg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-3.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"MULINO Y PRODUCTORES 3\" aria-label=\"MULINO Y PRODUCTORES 3\" class=\"img-responsive wp-image-101875\" srcset=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-3-200x133.jpeg 200w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-3-400x267.jpeg 400w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-3.jpeg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-4.jpeg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-4.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"MULINO Y PRODUCTORES 4\" aria-label=\"MULINO Y PRODUCTORES 4\" class=\"img-responsive wp-image-101876\" srcset=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-4-200x133.jpeg 200w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-4-400x267.jpeg 400w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-4.jpeg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-5.jpeg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-5.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"MULINO Y PRODUCTORES 5\" aria-label=\"MULINO Y PRODUCTORES 5\" class=\"img-responsive wp-image-101877\" srcset=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-5-200x133.jpeg 200w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-5-400x267.jpeg 400w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-5.jpeg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-6.jpeg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-6.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"MULINO Y PRODUCTORES 6\" aria-label=\"MULINO Y PRODUCTORES 6\" class=\"img-responsive wp-image-101878\" srcset=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-6-200x133.jpeg 200w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-6-400x267.jpeg 400w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-6.jpeg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-7.jpeg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-7.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"MULINO Y PRODUCTORES 7\" aria-label=\"MULINO Y PRODUCTORES 7\" class=\"img-responsive wp-image-101879\" srcset=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-7-200x133.jpeg 200w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-7-400x267.jpeg 400w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-7.jpeg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-8.jpeg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-8.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"MULINO Y PRODUCTORES 8\" aria-label=\"MULINO Y PRODUCTORES 8\" class=\"img-responsive wp-image-101880\" srcset=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-8-200x133.jpeg 200w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-8-400x267.jpeg 400w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-8.jpeg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-9.jpeg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-9.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"MULINO Y PRODUCTORES 9\" aria-label=\"MULINO Y PRODUCTORES 9\" class=\"img-responsive wp-image-101881\" srcset=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-9-200x133.jpeg 200w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-9-400x267.jpeg 400w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-9.jpeg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-10.jpeg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-10.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"MULINO Y PRODUCTORES 10\" aria-label=\"MULINO Y PRODUCTORES 10\" class=\"img-responsive wp-image-101882\" srcset=\"https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-10-200x133.jpeg 200w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-10-400x267.jpeg 400w, https:\/\/sertv.gob.pa\/nacionalfm\/wp-content\/uploads\/sites\/6\/2024\/11\/MULINO-Y-PRODUCTORES-10.jpeg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":101873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-101872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/101872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=101872"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/101872\/revisions"}],"predecessor-version":[{"id":101883,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/101872\/revisions\/101883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/101873"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=101872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=101872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=101872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}