{"id":18728,"date":"2017-03-02T15:52:21","date_gmt":"2017-03-02T15:52:21","guid":{"rendered":""},"modified":"2017-03-02T15:52:21","modified_gmt":"2017-03-02T15:52:21","slug":"el-ejercito-sirio-toma-la-ciudadela-de-palmira","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/el-ejercito-sirio-toma-la-ciudadela-de-palmira\/","title":{"rendered":"El Ej\u00e9rcito sirio toma la ciudadela de Palmira"},"content":{"rendered":"<p>\nEl Ej\u00e9rcito sirio tom\u00f3 hoy la ciudadela medieval de la urbe monumental de Palmira, ciudad donde desarrolla una ofensiva contra el grupo terrorista Estado Isl\u00e1mico (EI), inform\u00f3 la agencia oficial siria, SANA. <\/p>\n<p>La ciudadela se encuentra en un monte desde el que se dominan las ruinas grecorromanas y desde donde se divisa gran parte de la ciudad, que hasta ahora estaba bajo el control de los yihadistas. <\/p>\n<p>Las unidades castrenses tambi\u00e9n recuperaron hoy una colina en el oeste de la ciudad y un hotel en el sur y causaron numerosas bajas en las filas yihadistas, seg\u00fan SANA. <\/p>\n<p>El EI se retir\u00f3 hoy de la mayor parte de Palmira y, en su huida, coloc\u00f3 minas y bombas en numerosos puntos de la urbe, seg\u00fan informaciones del Observatorio Sirio de Derechos Humanos y de la agencia oficial. <\/p>\n<p>Los artificieros del Ej\u00e9rcito peinan la zona para tratar de desactivar los explosivos, mientras las unidades militares progresan lentamente para evitar sufrir bajas, seg\u00fan SANA. <\/p>\n<p>La ofensiva del Ej\u00e9rcito sirio, que cuenta con el apoyo de los bombardeos de la aviaci\u00f3n rusa, comenz\u00f3 el mi\u00e9rcoles desde el frente oeste de la ciudad, que es patrimonio mundial de la UNESCO. <\/p>\n<p>El grupo terrorista conquist\u00f3 Palmira en mayo de 2015 y fue expulsado ocho meses despu\u00e9s por los soldados sirios, pero volvi\u00f3 a recuperar el control de la antigua ciudad grecorromana el pasado diciembre. <\/p>\n<p>Durante su dominio, los yihadistas dinamitaron los templos de Bel y Bal Sham\u00edn, el frente esc\u00e9nico del teatro romano, el taetrapil\u00f3n, el arco del triunfo y numerosas estatuas del museo de la ciudad, acciones que fueron consideradas como \u00abcr\u00edmenes de guerra\u00bb por la UNESCO. <\/p>\n<p>Palmira fue en los siglos I y II d.C. uno de los centros culturales m\u00e1s importantes de la \u00e9poca y punto de encuentro de las caravanas en la Ruta de la Seda, que atravesaban el desierto del centro de Siria. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ej\u00e9rcito sirio tom\u00f3 hoy la ciudadela medieval de la <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/el-ejercito-sirio-toma-la-ciudadela-de-palmira\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":18729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-18728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/18728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=18728"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/18728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/18729"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=18728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=18728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=18728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}