{"id":27779,"date":"2018-04-11T14:04:27","date_gmt":"2018-04-11T14:04:27","guid":{"rendered":""},"modified":"2018-04-11T14:04:27","modified_gmt":"2018-04-11T14:04:27","slug":"realizan-taller-de-cohesion-social-y-resiliencia-en-las-comunidades","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/realizan-taller-de-cohesion-social-y-resiliencia-en-las-comunidades\/","title":{"rendered":"Realizan \u201cTaller de cohesi\u00f3n social y Resiliencia, en las comunidades\u201d"},"content":{"rendered":"<p>\nCon la finalidad de estudiar la forma en que las comunidades puedan fortalecer la cohesi\u00f3n e integraci\u00f3n social entre sus residentes, representantes de la Alcald\u00eda de Panam\u00e1 y la Direcci\u00f3n de Resiliencia, han organizado una serie de talleres pilotos en 6 comunidades del distrito capital. <\/p>\n<p>Estos talleres pilotos, se efectuar\u00e1n hasta agosto del presente a\u00f1o, las comunidades participantes son: Alcalde D\u00edaz, Ernesto C\u00f3rdoba, Tocumen, Pedregal, Pacora y Kuna Nega y aparte de ver los temas de cohesi\u00f3n e integraci\u00f3n social, se busca detectar los problemas sociales, procurar las soluciones pertinentes a estos y determinar los espacios de convivencia en las comunidades. <\/p>\n<p>Al respecto, el director de Resiliencia, Arturo Domenici, revel\u00f3, que &ldquo;este es un \u00e1rea de trabajo dentro de la estrategia de resiliencia que estamos llevando a cabo en la municipalidad de Panam\u00e1, junto con el Programa de Ciudades Resilientes, en procura de realizar una construcci\u00f3n efectiva de la resiliencia basados en el hecho de que para lograr resiliencia las personas tienen que conocerse e integrarse y que esta comienza por procesos de cohesi\u00f3n, identificaci\u00f3n y respeto mutuo&rdquo;. <\/p>\n<p>El programa de resiliencia, es coordinado por la\u00a0\u00a0 Asociaci\u00f3n Centro de Estudios y Acci\u00f3n Social Paname\u00f1o  (CEASPA),organizaci\u00f3n que tiene m\u00e1s de 60 a\u00f1os trabajando estos temas y est\u00e1 compuesta por soci\u00f3logos con amplia experiencia en temas sociales y comunitarios,\u00a0quien a trav\u00e9s de encuestas, cuestionarios, mapas de localizaci\u00f3n y trabajos en grupo realiza un dise\u00f1o de las actividades y \u00e1reas dentro de las comunidades (espacios p\u00fablicos, cohesi\u00f3n como parques, escuelas, parvularios o centros comunitarios)\u00a0que pueden facilitar o no la integraci\u00f3n de los ciudadanos y su visi\u00f3n de objetivos comunes suministrando oportunidades de verse e intercambiar ideas, planes, juegos y otras actividades a trav\u00e9s del arte , el deporte y la cultura. <\/p>\n<p>Un componente adicional recomendado por el alcalde Bland\u00f3n, radica en observar como los espacios de los proyectos que se est\u00e1n haciendo en ciertas \u00e1reas como veredas y aceras, pueden convertirse en puntos de partida para otras obras propuestas por la misma comunidad.\u00a0\u00a0No se les promete a las personas otras cosas, sino que estas se convierten en ocasiones para concebir ideas de otras cosas que se pueden planificar en el futuro. <\/p>\n<p>No obstante, el punto principal sigue siendo establecer cohesi\u00f3n comunitaria a trav\u00e9s de mapeo de \u00e1reas que podr\u00e1n producir cohesi\u00f3n elaborados por ellos mismos determinando los espacios propicios para este fin.\u00a0\u00a0El proceso de los talleres, es totalmente interactivo, al tiempo que procura producir informaci\u00f3n relevante para la comunidad en forma de formularios y encuestas, en grupo que van de 20 personas hasta cerca de 40. <\/p>\n<p>El grupo de trabajo que participa en los talleres, consiste en los funcionarios de la Direcci\u00f3n de Resiliencia, la Direcci\u00f3n de Participaci\u00f3n Ciudadana (log\u00edstica y convocatoria), la Direcci\u00f3n de Gesti\u00f3n Social (promotores) y la Direcci\u00f3n de Cultura y Educaci\u00f3n (parte t\u00e9cnica junto a CEASPA).\u00a0\u00a0El producto de estos talleres, ser\u00e1 un informe t\u00e9cnico que favorecer\u00e1 el trabajo elaborado por estas cuatro direcciones en sus respectivas \u00e1reas. <\/p>\n<p>Cabe se\u00f1alar, que la tarde del s\u00e1bado, cerca de 28 personas participaron en el taller de resiliencia desarrollado en Pacora, aportando sus opiniones, atendiendo y colaborando para dimensionar los problemas de este importante sector del este de la ciudad.\u00a0\u00a0Al final de la jornada, lleg\u00f3 la vicealcaldesa, Raisa Banfield, para acompa\u00f1arlos, escuchando y atendiendo algunas de sus solicitudes y comentarios. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la finalidad de estudiar la forma en que las <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/realizan-taller-de-cohesion-social-y-resiliencia-en-las-comunidades\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":27780,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=27779"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/27780"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=27779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=27779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=27779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}