{"id":27805,"date":"2018-04-12T14:11:12","date_gmt":"2018-04-12T14:11:12","guid":{"rendered":""},"modified":"2018-04-12T14:11:12","modified_gmt":"2018-04-12T14:11:12","slug":"nuevo-embajador-de-la-republica-de-belarus-entrega-copias-de-cartas-credenciales","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/nuevo-embajador-de-la-republica-de-belarus-entrega-copias-de-cartas-credenciales\/","title":{"rendered":"Nuevo Embajador de la Rep\u00fablica de Belar\u00fas, entrega copias de cartas credenciales"},"content":{"rendered":"<p>\nEl Ministro Encargado, Luis Miguel Hincapi\u00e9, recibi\u00f3 recientemente, las copias de cartas credenciales del nuevo Embajador de la Rep\u00fablica de Belar\u00fas, Igar Paluy\u00e1n, e intercambi\u00f3 el inter\u00e9s de la administraci\u00f3n del Presidente de la Rep\u00fablica de Panam\u00e1, Juan Carlos Varela de acercar y fortalecer las relaciones con el Medio Oriente, el Sudeste Asi\u00e1tico, India y \u00c1frica como parte de la Pol\u00edtica Halc\u00f3n, lanzada el mes pasado, en los Emiratos \u00c1rabes Unidos.\u00a0 <\/p>\n<p>Hincapi\u00e9, adem\u00e1s comparti\u00f3 el compromiso de Panam\u00e1, con los est\u00e1ndares de cooperaci\u00f3n internacional, destacando que el pa\u00eds es signatario del Acuerdo Multilateral de Autoridades Competentes para el Intercambio Autom\u00e1tico de Informaci\u00f3n Financiera para Fines Tributarios y del Convenio Multilateral para implementar medidas a fin de evitar la Erosi\u00f3n de la Base y el Traslado de Beneficios en materia fiscal.\u00a0 <\/p>\n<p>Al mismo tiempo, Hincapi\u00e9, extendi\u00f3 una invitaci\u00f3n a las empresas bielorrusas a que inviertan en nuestro pa\u00eds identificando nichos de negocios conforme a las facilidades que brinda el pa\u00eds como polo de alta conectividad, plataforma log\u00edstica y las actividades conexas relacionadas al Canal de Panam\u00e1, as\u00ed como su estabilidad socio-pol\u00edtica. <\/p>\n<p>Cabe recordar, que Panam\u00e1 y Bielorrusia, establecieron relaciones diplom\u00e1ticas, el 22 de octubre de 1998. La Embajada de la Rep\u00fablica de Panam\u00e1 en la Federaci\u00f3n de Rusia, es concurrente ante la Rep\u00fablica de Belar\u00fas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministro Encargado, Luis Miguel Hincapi\u00e9, recibi\u00f3 recientemente, las copias <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/nuevo-embajador-de-la-republica-de-belarus-entrega-copias-de-cartas-credenciales\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":27806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=27805"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/27806"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=27805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=27805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=27805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}