{"id":27831,"date":"2018-04-12T19:32:19","date_gmt":"2018-04-12T19:32:19","guid":{"rendered":""},"modified":"2018-04-12T19:32:19","modified_gmt":"2018-04-12T19:32:19","slug":"gobierno-coreano-muestra-interes-en-hub-humanitario-en-panama","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/gobierno-coreano-muestra-interes-en-hub-humanitario-en-panama\/","title":{"rendered":"Gobierno Coreano, muestra inter\u00e9s en \u201cHub Humanitario\u201d, en Panam\u00e1"},"content":{"rendered":"<p>\nEl Gobierno de la Rep\u00fablica de Corea del Sur, representado en su Embajada en Panam\u00e1, ha mostrado inter\u00e9s en apoyar el funcionamiento del Centro Log\u00edstico Regional de Asistencia Humanitaria (CLRAH). <\/p>\n<p>El coordinador del Centro Log\u00edstico Regional de Asistencia Humanitaria (CLRAH), Carlos G\u00f3mez, acompa\u00f1\u00f3 al primer secretario de la Embajada de Corea en Panam\u00e1, Jin-Hyun Kang, a un recorrido en el \u00e1rea occidental del aeropuerto de Panam\u00e1 Pac\u00edfico, donde se construye el Hub Humanitario sobre 6.12 hect\u00e1reas, cuyo avance es de un 74.9%. <\/p>\n<p>Como parte de la visita se recorri\u00f3 el edificio de administraci\u00f3n, as\u00ed como las instalaciones que est\u00e1n destinadas para uso del Sistema Nacional de Protecci\u00f3n Civil (SINAPROC). <\/p>\n<p>Cabe se\u00f1alar, que a trav\u00e9s de CLRAH, el Gobierno de Panam\u00e1, busca ejecutar una pol\u00edtica al servicio del desarrollo nacional en materia de reducci\u00f3n de riesgo de desastre y para la entrega oportuna de ayuda, en caso de desastres naturales y cat\u00e1strofes en Am\u00e9rica Latina y el Caribe. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de la Rep\u00fablica de Corea del Sur, representado <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/gobierno-coreano-muestra-interes-en-hub-humanitario-en-panama\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":27832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=27831"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/27832"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=27831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=27831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=27831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}