{"id":27861,"date":"2018-04-16T13:16:16","date_gmt":"2018-04-16T13:16:16","guid":{"rendered":""},"modified":"2018-04-16T13:16:16","modified_gmt":"2018-04-16T13:16:16","slug":"presidente-varela-alento-a-jovenes-de-america-a-ser-lideres-en-positivo","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/presidente-varela-alento-a-jovenes-de-america-a-ser-lideres-en-positivo\/","title":{"rendered":"Presidente Varela alent\u00f3 a j\u00f3venes de Am\u00e9rica a ser l\u00edderes en positivo"},"content":{"rendered":"<p>\nEl presidente de Panam\u00e1, Juan Carlos Varela, inst\u00f3 a los j\u00f3venes de Am\u00e9rica a siempre ser l\u00edderes en positivo, ya que para abrirse espacios en la vida p\u00fablica o privada no hay que destruir ni ofender, sino asegurar el bien com\u00fan. <\/p>\n<p>El Mandatario, en fecha reciente, fue el invitado de honor en el V Foro de J\u00f3venes de \u00a0las Am\u00e9ricas, a quienes inst\u00f3 a entrar a la vida p\u00fablica en sus pa\u00edses. &ldquo;Empiecen en sus comunidades, barrios, escuelas, empresas y crezcan. As\u00ed llegu\u00e9 a presidir un partido y a Presidente de la Rep\u00fablica en una carrera muy desigual&rdquo;, pronunci\u00f3. <\/p>\n<p>Relat\u00f3, que la semilla de servir a los dem\u00e1s naci\u00f3 en \u00e9l desde muy ni\u00f1o, cuando al llegar a clases en su colegio se encontr\u00f3 con el retrato de un sacerdote desaparecido (H\u00e9ctor Gallego) \u00a0en la \u00e9poca militar, que serv\u00eda en las monta\u00f1as de Veraguas en beneficio de los campesinos. <\/p>\n<p>&ldquo;Ese d\u00eda aprend\u00ed que se arriesga la vida sirviendo a los dem\u00e1s, pero como Presidente de la Rep\u00fablica hoy se construye una carretera que cruza por todas esas monta\u00f1as y hoy se la dedic\u00f3 a ese sacerdote&rdquo;, expres\u00f3. <\/p>\n<p>El Jefe de Estado, tambi\u00e9n comparti\u00f3 con los j\u00f3venes una serie de ense\u00f1anzas para ser hombres y mujeres de bien, entre ellas, ser leales al Estado, siempre tomar el camino correcto en la vida y \u00a0buscar el bien com\u00fan. &ldquo;Sean constructores de un mejor futuro para ustedes, sus familias, compa\u00f1eros y su pa\u00eds&rdquo;. <\/p>\n<p>El presidente Varela, destac\u00f3, que su Administraci\u00f3n lucha para que en Panam\u00e1 la pol\u00edtica sea un servicio y no un negocio, y ese ser\u00e1 el principal legado al finalizar su gesti\u00f3n. <\/p>\n<p>Adem\u00e1s, exterioriz\u00f3, que la lucha contra la desigualdad se gana trabajando unidos, sacando el tema de la corrupci\u00f3n, pero sin destruir empresas, econom\u00edas y pa\u00edses, sino transformando. <\/p>\n<p>&ldquo;Panam\u00e1, es un pa\u00eds que avanza con crecimiento econ\u00f3mico del 6%, inversi\u00f3n p\u00fablica grand\u00edsima, se construyen hospitales y escuelas porque se recuper\u00f3 el Canal que aporta 1,700 millones de d\u00f3lares al Estado. Con esos fondos se construye infraestructura inclusiva que impacta la calidad de vida de las personas, como de edificaci\u00f3n de 100 mil casas nuevas para que nadie se queda atr\u00e1s con el progreso del pa\u00eds&rdquo;, indic\u00f3. <\/p>\n<p>Durante la actividad, el Gobernante recibi\u00f3 -por segunda ocasi\u00f3n- la Declaratoria de Compromiso de \u00a0los J\u00f3venes de \u00a0las Am\u00e9ricas, la cual estipula que para la consecuci\u00f3n de los Objetivos de Desarrollo Sostenible de \u00a0la Agenda 2030 de las Naciones Unidas, los j\u00f3venes desean participar &ndash;como embajadores del cambio- en los temas que la transparencia de los gobiernos y de los sectores que influyen en la gobernabilidad democr\u00e1tica de los pa\u00edses <\/p>\n<p> Invitaci\u00f3n a la JMJ  <\/p>\n<p>El presidente Varela, tambi\u00e9n invit\u00f3 a los cientos de asistentes al V Foro de J\u00f3venes de las Am\u00e9ricas, a la Jornada Mundial de la Juventud (JMJ), a desarrollarse en Panam\u00e1, del 22 al 27 de enero de 2019 y que ser\u00e1 una Jornada de Centroam\u00e9rica y de todo el continente. <\/p>\n<p>&ldquo;Este ser\u00e1 un encuentro de fe, amistad y esperanza, en el que los j\u00f3venes tendr\u00e1n la oportunidad de compartir como hermanos y recibir la visita de un gran l\u00edder del mundo, el Papa Francisco&rdquo;, afirm\u00f3.\u00a0 <\/p>\n<p>Para el \u00e9xito de esta actividad, un gran equipo, con mucha responsabilidad y humildad, se ha preparado para la llegada de m\u00e1s de 300 mil j\u00f3venes al pa\u00eds. <\/p>\n<p>En este foro, el presidente Varela estuvo acompa\u00f1ado por la vicepresidenta y canciller, Isabel de Saint Malo de Alvarado; el ministro \u00a0de Econom\u00eda y Finanzas, Dulcidio De La Guardia y la embajadora de Panam\u00e1 en Per\u00fa, Nicole Wolcovinsky. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Panam\u00e1, Juan Carlos Varela, inst\u00f3 a los <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/presidente-varela-alento-a-jovenes-de-america-a-ser-lideres-en-positivo\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":27862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=27861"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/27862"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=27861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=27861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=27861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}