{"id":27889,"date":"2018-04-17T12:38:38","date_gmt":"2018-04-17T12:38:38","guid":{"rendered":""},"modified":"2018-04-17T12:38:38","modified_gmt":"2018-04-17T12:38:38","slug":"programa-mundial-de-alimentos-abre-vacante-para-cargo-en-su-sede-roma","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/programa-mundial-de-alimentos-abre-vacante-para-cargo-en-su-sede-roma\/","title":{"rendered":"Programa Mundial de Alimentos abre vacante para cargo en su sede, Roma"},"content":{"rendered":"<p>\nEl Ministerio de Relaciones Exteriores tiene el agrado de informar que el Programa Mundial de Alimentos (PMA), ha abierto una vacante para el cargo de Subdirector Ejecutivo del Departamento de Asociaciones y Gobernanza, con car\u00e1cter permanente en su sede Roma. <\/p>\n<p>Entre otros requisitos, el candidato debe tener t\u00edtulo universitario superior (o t\u00edtulo equivalente a un m\u00e1ster) en econom\u00eda, gesti\u00f3n, administraci\u00f3n de empresas, diplomacia, comunicaciones, gobernanza empresarial, ciencias pol\u00edticas, relaciones internacionales, derecho internacional del desarrollo u otra esfera pertinente; 20 a\u00f1os de experiencia profesional, s\u00f3lido sentido de diplomacia, conocimiento del contexto en el que opera el PMA y gran capacidad empresarial. Adem\u00e1s debe tener excelente dominio del idioma ingl\u00e9s y es conveniente que tenga conocimiento pr\u00e1ctico de un segundo idioma oficial de las Naciones Unidas (\u00e1rabe, chino, espa\u00f1ol, franc\u00e9s o ruso) o del portugu\u00e9s (uno de los idiomas de trabajo del PMA). <\/p>\n<p>Al candidato seleccionado se le ofrecer\u00e1 un contrato de plazo fijo con un per\u00edodo de prueba de un a\u00f1o. El PMA ofrece una remuneraci\u00f3n y un conjunto de prestaciones atractivos, que incluye sueldo b\u00e1sico, ajuste por lugar de destino, prestaciones por traslado, prestaciones de viaje y mudanza, 30 d\u00edas de vacaciones anuales, viajes al pa\u00eds de origen y subsidios de educaci\u00f3n para hijos a cargo, plan de pensiones y seguro m\u00e9dico. <\/p>\n<p>Todas las solicitudes deber\u00e1n incluir una carta de presentaci\u00f3n y el curr\u00edculo del candidato y habr\u00e1n de presentarse a trav\u00e9s del sitio web del PMA dedicado a las oportunidades de empleo antes del 12 de mayo de 2018. <\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n consulte el sitio web siguiente: icsc.un.org <\/p>\n<p>El Gobierno de Panam\u00e1 promueve la participaci\u00f3n de paname\u00f1os en organismos internacionales, con la finalidad de poner al servicio de la comunidad internacional la experiencia y competencia de sus profesionales y lograr un mayor posicionamiento de las fortalezas de Panam\u00e1 en el exterior. <\/p>\n<p>\u00a0 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Relaciones Exteriores tiene el agrado de informar <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/programa-mundial-de-alimentos-abre-vacante-para-cargo-en-su-sede-roma\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":27890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=27889"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/27890"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=27889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=27889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=27889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}