{"id":27915,"date":"2018-04-17T18:49:47","date_gmt":"2018-04-17T18:49:47","guid":{"rendered":""},"modified":"2018-04-17T18:49:47","modified_gmt":"2018-04-17T18:49:47","slug":"estudiantes-en-la-provincia-de-chiriqui-recibiran-orientacion-del-pove","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/estudiantes-en-la-provincia-de-chiriqui-recibiran-orientacion-del-pove\/","title":{"rendered":"Estudiantes en la provincia de Chiriqu\u00ed, recibir\u00e1n orientaci\u00f3n del POVE"},"content":{"rendered":"<p>\nM\u00e1s de 600 estudiantes graduandos de los distritos de Bar\u00fa, San F\u00e9lix y Tol\u00e9, en la provincia de Chiriqu\u00ed ser\u00e1n instruidos por el personal t\u00e9cnico del Programa de Orientaci\u00f3n Vocacional y Empleo (POVE) del Ministerio de Trabajo y Desarrollo Laboral (MITRADEL) sobre las profesiones m\u00e1s prometedoras para el mercado laboral del pa\u00eds. <\/p>\n<p>Acorde a Publio Caballero, jefe nacional del POVE, del 17 al 20 de abril,\u00a0 estar\u00e1n visitando los colegios Secundario de Puerto Armuelles y el Instituto de Puerto Armuelles, en el distrito del Bar\u00fa; mientras que se har\u00e1 lo propio en el Colegio Comercial Tol\u00e9 y el Secundario de Las Lajas en el distrito de San F\u00e9lix. <\/p>\n<p>&ldquo;Con el POVE, los j\u00f3venes que cursan sus estudios de premedia y media conocen hacia d\u00f3nde va orientada la necesidad de mano de obra para nuestro pa\u00eds; y ese es el principal objetivo de MITRADEL que ellos cuenten con informaci\u00f3n actual que les permita decidir por una carrera que les contribuya a desarrollarse como profesionales&rdquo;, resalt\u00f3 Caballero. <\/p>\n<p>Cabe recordar, que el POVE, beneficia a j\u00f3venes entre los 16 a 18 a\u00f1os de edad, los motiva a estudiar carreras que van a tener mayores oportunidades de inserci\u00f3n en el mercado paname\u00f1o en los pr\u00f3ximos a\u00f1os. <\/p>\n<p>Este programa, nace como una iniciativa del\u00a0 Ministro de Trabajo,\u00a0 Luis Ernesto Carles, a fin de orientar vocacionalmente a los j\u00f3venes del pa\u00eds para que sepan de primera mano, cu\u00e1les son las carreras y ocupaciones que se perfilan entre las m\u00e1s prometedoras por los pr\u00f3ximos cinco a\u00f1os seg\u00fan el diagn\u00f3stico que refleja el informe de la Alta Comisi\u00f3n de Pol\u00edticas P\u00fablicas de Empleo, el cual fue entregado al ejecutivo en noviembre del 2017. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 600 estudiantes graduandos de los distritos de Bar\u00fa, <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/estudiantes-en-la-provincia-de-chiriqui-recibiran-orientacion-del-pove\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":27916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=27915"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/27916"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=27915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=27915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=27915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}