{"id":27917,"date":"2018-04-17T19:36:07","date_gmt":"2018-04-17T19:36:07","guid":{"rendered":""},"modified":"2018-04-17T19:36:07","modified_gmt":"2018-04-17T19:36:07","slug":"acp-efectuara-mantenimiento-en-potabilizadora-de-mendoza-este-martes","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/acp-efectuara-mantenimiento-en-potabilizadora-de-mendoza-este-martes\/","title":{"rendered":"ACP efectuar\u00e1 mantenimiento en potabilizadora de Mendoza, este martes"},"content":{"rendered":"<p>\nLa Autoridad del Canal de Panam\u00e1 inform\u00f3 al IDAAN que por trabajos de mantenimiento preventivo, la planta potabilizadora de Mendoza estar\u00e1 operando a un 75% de su capacidad. Los trabajos iniciar\u00e1n a las 10:00 p.m. de este martes, 17 de abril y culminar\u00e1n a las 8:00 a.m. de ma\u00f1ana mi\u00e9rcoles, 18 de abril. <\/p>\n<p>Al disminuir la producci\u00f3n de agua potable en la planta potabilizadora de Mendoza, podr\u00eda registrarse baja presi\u00f3n o falta del suministro de agua en Arraij\u00e1n en el corregimiento Juan Dem\u00f3stenes Arosemena, Vista Alegre y en La Chorrera en el corregimiento de Guadalupe, El Coco, Playa Leona y \u00e1reas aleda\u00f1as. <\/p>\n<p>La producci\u00f3n de agua potable de la planta potabilizadora de Mendoza es responsabilidad de la ACP, el IDAAN, le compra agua en bloque y la env\u00eda a trav\u00e9s de la red de distribuci\u00f3n a la poblaci\u00f3n, es por ello que la ACP se encarga de realizar los trabajos de mantenimiento que sean necesarios para mantener las instalaciones en \u00f3ptimas condiciones. <\/p>\n<p>Por recomendaciones de la ACP y del IDAAN, se exhorta a hacer un uso racional del agua y tomar las medidas necesarias para evitar el desabastecimiento durante el tiempo que duren los trabajos y se recupere el sistema. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Autoridad del Canal de Panam\u00e1 inform\u00f3 al IDAAN que <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/acp-efectuara-mantenimiento-en-potabilizadora-de-mendoza-este-martes\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":27918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=27917"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/27917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/27918"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=27917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=27917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=27917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}