{"id":32916,"date":"2018-11-30T14:54:19","date_gmt":"2018-11-30T14:54:19","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=32916"},"modified":"2018-11-30T14:54:19","modified_gmt":"2018-11-30T14:54:19","slug":"entidades-gubernamentales-dictan-taller-sobre-pobreza-multidimensional","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/entidades-gubernamentales-dictan-taller-sobre-pobreza-multidimensional\/","title":{"rendered":"Entidades gubernamentales dictan taller sobre Pobreza Multidimensional"},"content":{"rendered":"<p>Un estudio sobre los \u00cdndices de Pobreza Multidimensional de Panam\u00e1, fue mostrado, en fecha reciente, por personal del Ministerio de Desarrollo Social (MIDES) a miembros de la Asociaci\u00f3n de Ejecutivos de Empresa (APEDE), cap\u00edtulo de Col\u00f3n, C\u00e1mara de Comercio y a la Direcci\u00f3n de Cultura y Juventud del municipio de Col\u00f3n.<\/p>\n<p>Ana Carolina D\u00edaz, coordinadora de este proyecto y, quien en representaci\u00f3n de la Ministra del MIDES, Michelle Muschett, fue la responsable de ofrecer la informaci\u00f3n a los concurrentes, revel\u00f3, que el concepto de pobreza multidimensional, toma en consideraci\u00f3n, no s\u00f3lo el aspecto de los ingresos, sino que de modo integral las m\u00faltiples privaciones y carencias que experimentan simult\u00e1neamente las personas y los hogares en m\u00faltiples dimensiones del bienestar tales como: salud, educaci\u00f3n, trabajo, medio ambiente, nivel de vida, entre otros.<\/p>\n<p>Para Gilberto Mena, presidente de APEDE Col\u00f3n, este tema es de suma importancia para la sociedad, pues pude servir de herramienta en la b\u00fasqueda de estrategias, tanto para la clase pol\u00edtica, como para el sector empresarial, a fin de enfrentar las diversas situaciones que en general se convierte en el freno del desarrollo de los pueblos.<\/p>\n<p>Mientras tanto, Abel Aronategui de la direcci\u00f3n de Juventud y Cultura del Municipio de Col\u00f3n, se refiere a las estad\u00edsticas ofrecidas en el informe de pobreza multidimensional y c\u00f3mo a trav\u00e9s de la descentralizaci\u00f3n pueden abordar la multi-dimensionalidad de los diferentes aspectos que inciden en declarar pobre a una cierta regi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un estudio sobre los \u00cdndices de Pobreza Multidimensional de Panam\u00e1, <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/entidades-gubernamentales-dictan-taller-sobre-pobreza-multidimensional\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":32917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-32916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/32916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=32916"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/32916\/revisions"}],"predecessor-version":[{"id":32918,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/32916\/revisions\/32918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/32917"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=32916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=32916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=32916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}