{"id":33069,"date":"2018-12-04T19:15:57","date_gmt":"2018-12-04T19:15:57","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=33069"},"modified":"2018-12-04T19:15:57","modified_gmt":"2018-12-04T19:15:57","slug":"jovenes-unidos-por-la-educacion-y-canal-de-panama-realizaran-ii-encuentro","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/jovenes-unidos-por-la-educacion-y-canal-de-panama-realizaran-ii-encuentro\/","title":{"rendered":"J\u00f3venes Unidos por la Educaci\u00f3n y Canal de Panam\u00e1 realizar\u00e1n II encuentro"},"content":{"rendered":"<p><strong>\u201cJ\u00f3venes Unidos por la Educaci\u00f3n y la Autoridad del Canal de Panam\u00e1\u201d <\/strong>efectuar\u00e1n, el jueves, 6 de diciembre, el segundo encuentro <strong>\u201cEl Papel de la Juventud en el futuro del Canal de Panam\u00e1\u201d, <\/strong>con la finalidad de compartir ideas y analizar los retos actuales y futuros de la ruta interoce\u00e1nica.<\/p>\n<p>El evento, est\u00e1 orientado a j\u00f3venes entre los 15 y 30 a\u00f1os, y tendr\u00e1 lugar en la sede del Parlamento Centroamericano y Caribe\u00f1o (PARLATINO), en la entrada de la Calzada de Amador.<\/p>\n<p>Esta es la segunda ocasi\u00f3n en que los j\u00f3venes tendr\u00e1n la oportunidad de compartir con algunos de los protagonistas de la historia y del presente Canal, quienes han participado en su evoluci\u00f3n y \u00e9xito. El primer encuentro se llev\u00f3 a cabo el 15 de agosto de 2017.<\/p>\n<p>El foro, no s\u00f3lo tiene como objetivo compartir con los j\u00f3venes informaci\u00f3n \u00fatil y confiable, sino tambi\u00e9n invitarlos a que se involucren de manera activa en las decisiones futuras a fin de asegurar la competitividad y el valor de la ruta interoce\u00e1nica.<\/p>\n<p><strong>El encuentro abarcar\u00e1 los siguientes aspectos:<\/strong><\/p>\n<ul>\n<li>Presentaciones para poner en contexto los temas m\u00e1s relevantes del Canal, los retos que enfrenta y cu\u00e1les son las perspectivas a corto y largo plazo.<\/li>\n<li>Mesas de trabajo sobre tres ejes tem\u00e1ticos fundamentales para el futuro del Canal: Institucionalidad, Competitividad y Sostenibilidad.<\/li>\n<li>Plenaria con los representantes de equipo, uno de cada eje tem\u00e1tico, y un panel integrado por expertos, incluyendo al administrador del Canal de Panam\u00e1.<\/li>\n<\/ul>\n<p>La conclusi\u00f3n de esta jornada, se resumir\u00e1 en la firma de un compromiso intergeneracional, con el objetivo de que sea parte de la toma de decisiones del futuro.<\/p>\n<p><strong>Cabe resaltar, que los j\u00f3venes que deseen participar deben registrarse a trav\u00e9s del siguiente enlace:\u00a0<a href=\"https:\/\/micanaldepanama.com\/juventud\/\" target=\"_blank\" rel=\"noopener\">https:\/\/micanaldepanama.com\/juventud\/<\/a>.<\/strong><\/p>\n<p><strong>Las inscripciones ser\u00e1n recibidas hasta las 11:59 p.m. de este martes, 4 de diciembre.<\/strong><\/p>\n<p><strong>En caso de menores de edad, deber\u00e1n tener autorizaci\u00f3n de sus padres o tutores para trasladarse a la ciudad capital y participar.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cJ\u00f3venes Unidos por la Educaci\u00f3n y la Autoridad del Canal <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/jovenes-unidos-por-la-educacion-y-canal-de-panama-realizaran-ii-encuentro\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":33070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=33069"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33069\/revisions"}],"predecessor-version":[{"id":33071,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33069\/revisions\/33071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/33070"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=33069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=33069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=33069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}