{"id":33089,"date":"2018-12-05T16:27:46","date_gmt":"2018-12-05T16:27:46","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=33089"},"modified":"2018-12-05T16:27:46","modified_gmt":"2018-12-05T16:27:46","slug":"up-de-panama-efectua-reunion-para-tramitar-examenes-internacionales-toefl-ibt-gre","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/up-de-panama-efectua-reunion-para-tramitar-examenes-internacionales-toefl-ibt-gre\/","title":{"rendered":"UP de Panam\u00e1 efect\u00faa reuni\u00f3n para tramitar ex\u00e1menes internacionales: TOEFL, iBT, GRE"},"content":{"rendered":"<p>La Direcci\u00f3n General de Planificaci\u00f3n y Evaluaci\u00f3n Universitaria, en conjunto con la Facultad de Humanidades, desde el a\u00f1o 2017, promueven el proyecto:\u00a0<strong>\u201cUniversidad de Panam\u00e1, Centro Autorizado para gestionar los ex\u00e1menes internacionales: TOEFL, iBT, GRE\u201d.<\/strong><\/p>\n<p>Por consiguiente, se sostuvo reuni\u00f3n a trav\u00e9s de videoconferencia con la doctora Sorani Mar\u00edn, representante a nivel regional (M\u00e9xico, Honduras, Costa Rica, Colombia, Cuba y Panam\u00e1) de la empresa ETS (por sus siglas en ingl\u00e9s), con la finalidad de esclarecer dudas e inquietudes en lo que concierne al proceso de certificaci\u00f3n en aras de formalizar esta importante iniciativa de inter\u00e9s interinstitucional.<\/p>\n<p>Para esta cita, se cont\u00f3 con la presencia de la mag\u00edster Leidiana Hill, Vicedecana de la Facultad de Humanidades y un equipo de docentes del Centro de Lenguas; as\u00ed como la mag\u00edster Yira E. P\u00e9rez Naranjo, Directora General de Planificaci\u00f3n y Evaluaci\u00f3n Universitaria y su equipo, que incluye al Departamento de Desarrollo Institucional, responsables de impulsar y dar el acompa\u00f1amiento t\u00e9cnico al proyecto en referencia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n General de Planificaci\u00f3n y Evaluaci\u00f3n Universitaria, en conjunto <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/up-de-panama-efectua-reunion-para-tramitar-examenes-internacionales-toefl-ibt-gre\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":33090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=33089"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33089\/revisions"}],"predecessor-version":[{"id":33091,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33089\/revisions\/33091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/33090"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=33089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=33089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=33089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}