{"id":33103,"date":"2018-12-05T19:41:42","date_gmt":"2018-12-05T19:41:42","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=33103"},"modified":"2018-12-05T19:42:37","modified_gmt":"2018-12-05T19:42:37","slug":"medicos-y-enfermeras-de-epidemiologia-se-capacitan-a-nivel-nacional","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/medicos-y-enfermeras-de-epidemiologia-se-capacitan-a-nivel-nacional\/","title":{"rendered":"M\u00e9dicos y Enfermeras de Epidemiolog\u00eda se capacitan a nivel nacional"},"content":{"rendered":"<p>Enfermeras (os) y m\u00e9dicos que laboran en las \u00e1reas de epidemiolog\u00eda institucional, hospitalario y local (Policl\u00ednicas, ULAPS y CAPPS) a nivel nacional, participaron de la reuni\u00f3n t\u00e9cnico, administrativa-docente organizada por representantes del Departamento Nacional de Epidemiolog\u00eda de la Caja de Seguro Social (CSS).<\/p>\n<p>La Mgter. Annette Craig W., coordinadora nacional del Departamento de Epidemiolog\u00eda, indic\u00f3, que esta actividad fue para destacar la labor y el rol de la enfermera (o) en las actividades que desarrollan en la vigilancia epidemiol\u00f3gica, los mismos mantendr\u00e1n conocimientos unificados y actualizados. Estos aspectos permiten las intervenciones oportunas que conlleva al fortalecimiento a la atenci\u00f3n al usuario.<\/p>\n<p>Vigilancia epidemiol\u00f3gica, es determinar las acciones oportunas y de seguimiento que permiten resolver la problem\u00e1tica de salud que aqueja al paciente y a la poblaci\u00f3n en su momento, a\u00f1adi\u00f3 Craig.<\/p>\n<p>La epidemiolog\u00eda, est\u00e1 integrado por un equipo multidisciplinario, (m\u00e9dico, enfermera (o), trabajo social, farmac\u00e9utico, laboratoristas, estad\u00edsticas entre otras), que para el a\u00f1o 2019, y se tiene la expectativa que todo lo expuesto en esta docencia ser\u00e1 para fortalecer el departamento. Adem\u00e1s, la proyecci\u00f3n de las campa\u00f1as de prevenci\u00f3n que se llevan a cabo a nivel de las diferentes unidades incluyendo las hospitalarias acorde a las enfermedades que se vayan presentando.<\/p>\n<p>Algunos de los temas tratados fueron: Importancia de la bioseguridad en la vigilancia Epidemiol\u00f3gica para el personal de salud, Vigilancia epidemiol\u00f3gica como clave en las Arbovirosis, Manejo y seguimiento del paciente con TB \u2013 VIH al egreso hospitalario, C\u00f3mo afecta la notificaci\u00f3n, seguimiento y tratamiento no oportuno en los casos de Leishmaniasis y Chagas, entre otros.<\/p>\n<p>Durante la actividad, se le hizo un reconocimiento a dos enfermeras, que fortalecieron y fueron un pilar en la Vigilancia Epidemiol\u00f3gica en los niveles institucionales y locales: las licenciadas Luz P\u00e9rez y Martha Corbal\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enfermeras (os) y m\u00e9dicos que laboran en las \u00e1reas de <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/medicos-y-enfermeras-de-epidemiologia-se-capacitan-a-nivel-nacional\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":33104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=33103"}],"version-history":[{"count":2,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33103\/revisions"}],"predecessor-version":[{"id":33106,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33103\/revisions\/33106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/33104"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=33103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=33103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=33103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}