{"id":33622,"date":"2018-12-21T14:08:43","date_gmt":"2018-12-21T14:08:43","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=33622"},"modified":"2018-12-21T14:08:43","modified_gmt":"2018-12-21T14:08:43","slug":"65-de-evolucion-muestra-el-puente-peatonal-de-la-utp","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/65-de-evolucion-muestra-el-puente-peatonal-de-la-utp\/","title":{"rendered":"65% de evoluci\u00f3n muestra el Puente Peatonal de la UTP"},"content":{"rendered":"<p>La edificaci\u00f3n del paso elevado peatonal que se sit\u00faa entre las instalaciones de la Universidad Tecnol\u00f3gica de Panam\u00e1 (UTP) y el Centro de Rehabilitaci\u00f3n Especial (CRI), sobre la carretera Centenario muestra al presente, \u00a0un adelanto f\u00edsico de 65%. Estas cifras se reflejan al culminarse la construcci\u00f3n de m\u00e1s de quinientos (500) metros cuadrados de aceras peatonales de 1.20, 3.40, 4.40 metros de ancho hacia el acceso de la UTP y el CRI.<\/p>\n<p>Respecto a las dos estructuras que contemplan los apoyos de la cercha \u00a0del puente peatonal, en la que se ubica frente al CRI se ha construido el piso de la planta baja, las losas del primer y segundo nivel, la rampa de acceso hasta el primer nivel y la escalera hasta el primer nivel, ochos pilas, vigas transversales y el muro del elevador. En esta estructura de apoyo, falta por construir la rampa que comunica al segundo nivel, y la escalera del primer nivel hacia el segundo nivel.<\/p>\n<p>En la estructura de apoyo del lado de la UTP, se ha levantado el piso de la planta baja, el 30% de la rampa hasta el primer nivel, 6 pilas y las vigas transversales. Resta por edificar en este apoyo, la culminaci\u00f3n de la rampa hasta el primer nivel, la rampa que comunica desde el descanso uno hasta el segundo nivel, el muro del elevador y la losa del segundo piso.<\/p>\n<p>Para esta gesti\u00f3n, la empresa contratista cuenta con un plazo de 240 d\u00edas para\u00a0desarrollar los trabajos de este puente, el cual tendr\u00e1 una longitud de 35 metros, con rampas, escaleras, ascensor y un muro de\u00a0contenci\u00f3n.<\/p>\n<p>Este proyecto es ejecutado por personal del Ministerio de Obras P\u00fablicas (MOP), con una inversi\u00f3n de B\/.1,735,272.50, a trav\u00e9s de la empresa contratista ITECPA.<\/p>\n<p>La construcci\u00f3n de este nuevo paso elevado peatonal tiene como base la aplicaci\u00f3n de \u201ctipolog\u00eda de cerchas\u201d con perfiles tubulares de acero soportados mediante marcos de acero y pedestales de hormig\u00f3n.\u00a0Estos a su vez, dar\u00e1n soporte a un sistema de escaleras y rampas con estructuras de perfiles de acero y losas de l\u00e1minas colaborante del tipo metaldeck.<\/p>\n<p>Es importante resaltar, que esta nueva infraestructura\u00a0naci\u00f3 como una iniciativa de inversi\u00f3n del MOP, con la finalidad de obtener un dise\u00f1o que resuelva la problem\u00e1tica de movilidad peatonal de los pacientes que van al Complejo Instituto Nacional Medicina F\u00edsica y Rehabilitaci\u00f3n, adem\u00e1s de permitir un tr\u00e1fico fluido en esta zona de la v\u00eda Centenario y brindarles seguridad vial a los estudiantes de esta casa de estudios.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La edificaci\u00f3n del paso elevado peatonal que se sit\u00faa entre <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/65-de-evolucion-muestra-el-puente-peatonal-de-la-utp\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":33624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=33622"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33622\/revisions"}],"predecessor-version":[{"id":33625,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33622\/revisions\/33625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/33624"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=33622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=33622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=33622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}