{"id":33630,"date":"2018-12-21T15:46:59","date_gmt":"2018-12-21T15:46:59","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=33630"},"modified":"2018-12-21T15:46:59","modified_gmt":"2018-12-21T15:46:59","slug":"miviot-aprueba-edificacion-de-10-proyectos-en-ventanilla-unica-en-diversas-provincias","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/miviot-aprueba-edificacion-de-10-proyectos-en-ventanilla-unica-en-diversas-provincias\/","title":{"rendered":"MIVIOT aprueba edificaci\u00f3n de 10 proyectos en Ventanilla \u00danica en diversas provincias"},"content":{"rendered":"<p>Representantes de la Direcci\u00f3n de Ventanilla \u00danica del Ministerio de Vivienda y Ordenamiento Territorial de la Rep\u00fablica de Panam\u00e1 (MIVIOT), aprob\u00f3, en el mes de noviembre, un total de 10 proyectos con norma RBS y RBE en diferentes provincias, con los que se busca favorecer un total de 3 mil 24 familias.<\/p>\n<p>Para Panam\u00e1 Oeste, fueron aprobadas la construcci\u00f3n de mil 97 soluciones habitacionales en los corregimientos de Guadalupe, El Harado y Herrera en el distrito de La Chorrera, as\u00ed como\u00a0Vista Alegre en el distrito de Arraij\u00e1n.<\/p>\n<p>Mientras que, para la provincia de Cocl\u00e9, se aval\u00f3 la edificaci\u00f3n de 424 viviendas, las cuales\u00a0ser\u00e1n construidas en los corregimientos de Ant\u00f3n cabecera, Aguadulce cabecera y El Coco en el distrito de Penonom\u00e9.<\/p>\n<p>Por otra parte, en Chiriqu\u00ed, 325 casas a construir en el corregimiento de Los Algarrobos en el distrito de Dolega. Entretanto, en\u00a0Veraguas, se efectuar\u00e1 la edificaci\u00f3n de 134 viviendas, para el corregimiento de Canto del Llano en el distrito de Santiago.<\/p>\n<p>Cabe enfatizar, que los proyectos desarrollados en Panam\u00e1 bajo esta norma, forman parte de los que se encuentran afiliados al programa Fondo Solidario de Vivienda, que lleva a cabo la Direcci\u00f3n de Promoci\u00f3n para la Inversi\u00f3n Privada y que otorga el beneficio de los 10 mil balboas a las familias para la obtenci\u00f3n de la primera casa.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Representantes de la Direcci\u00f3n de Ventanilla \u00danica del Ministerio de <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/miviot-aprueba-edificacion-de-10-proyectos-en-ventanilla-unica-en-diversas-provincias\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":33632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=33630"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33630\/revisions"}],"predecessor-version":[{"id":33633,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33630\/revisions\/33633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/33632"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=33630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=33630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=33630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}