{"id":33634,"date":"2018-12-21T15:55:46","date_gmt":"2018-12-21T15:55:46","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=33634"},"modified":"2018-12-21T15:55:46","modified_gmt":"2018-12-21T15:55:46","slug":"sector-energetico-comparten-conocimientos-en-visperas-a-la-jmj-2019-en-panama","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/sector-energetico-comparten-conocimientos-en-visperas-a-la-jmj-2019-en-panama\/","title":{"rendered":"Sector energ\u00e9tico comparten conocimientos en v\u00edsperas a la JMJ 2019, en Panam\u00e1"},"content":{"rendered":"<p>El equipo t\u00e9cnico del sector energ\u00e9tico (ENSA, Naturgy y ETESA), se reunieron recientemente, con el viceministro de seguridad, Omar Pinz\u00f3n y Carlos S\u00e1nchez F\u00e1brega, presidente de la Junta Directiva de Transporte Masivo de Panam\u00e1, a fin de complementar el plan de contingencia durante la jornada Mundial de la Juventud JMJ) a celebrarse en la Rep\u00fablica de Panam\u00e1, del 22 al 27 de enero.<\/p>\n<p>La intenci\u00f3n es intercambiar ideas, conocimientos y unir criterios en base al cronograma y ruta trazada, para garantizar y fortalecer el sistema energ\u00e9tico utilizando todas la tecnolog\u00eda y medidas de fuerza mayor.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo t\u00e9cnico del sector energ\u00e9tico (ENSA, Naturgy y ETESA), <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/sector-energetico-comparten-conocimientos-en-visperas-a-la-jmj-2019-en-panama\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":33636,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=33634"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33634\/revisions"}],"predecessor-version":[{"id":33637,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33634\/revisions\/33637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/33636"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=33634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=33634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=33634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}