{"id":33640,"date":"2018-12-21T17:05:25","date_gmt":"2018-12-21T17:05:25","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=33640"},"modified":"2018-12-21T17:05:25","modified_gmt":"2018-12-21T17:05:25","slug":"tres-empresas-muestran-interes-por-rehabilitar-via-centenario-nuevo-emperador","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/tres-empresas-muestran-interes-por-rehabilitar-via-centenario-nuevo-emperador\/","title":{"rendered":"Tres empresas muestran inter\u00e9s por rehabilitar v\u00eda Centenario-Nuevo Emperador"},"content":{"rendered":"<p>El Ministerio de Obras Publicas llev\u00f3 a cabo, \u00a0el jueves, 20 de diciembre de 2018, la licitaci\u00f3n por mejor valor del proyecto \u201cDise\u00f1o y construcci\u00f3n para la rehabilitaci\u00f3n de la carretera entre la v\u00eda Centenario \u2013 Nuevo Emperador, en Panam\u00e1 Oeste\u201d.<\/p>\n<p>Para este acto de licitaci\u00f3n se cont\u00f3 con la presencia de tres empresas proponentes, las cuales hicieron entrega de sus propuestas a tiempo del vencimiento del t\u00e9rmino conforme a lo establecido en el pliego de cargos. La convocatoria comenz\u00f3 con la apertura del sobre del precio estimado por autoridades del MOP para el proyecto, el cual asciende a B\/. 17, 639,799.67.<\/p>\n<p>Las empresas proponentes fueron: Asfaltos Paname\u00f1os con una oferta de B\/.18,950,000.00; Constructora MECO S.A. la cual hizo una propuesta de B\/.18,918,803.49 y el consorcio Asociaci\u00f3n Accidental C&amp;T Nuevo Emperador (Toronto Global Holding Corp y Constructora de Infraestructura Internacional S.A. (ciisa) con una oferta de B\/. 19,320,990.00.<\/p>\n<p>El proyecto consta de una longitud de 15.45 kil\u00f3metros, el cual inicia en la v\u00eda de acceso a la cantera Rock Industries, S.A. por la carretera Centenario, y termina en la intersecci\u00f3n con la carretera de Nuevo Emperador; esto incluye la carretera entre la V\u00eda Centenario \u2013 Nuevo Emperador de 12.4 Kil\u00f3metros, adem\u00e1s del ramal hacia Burunga de 2.55 Kil\u00f3metros y salida hacia la v\u00eda Centenario que comprende 0.5 Kil\u00f3metros. Dentro del proyecto se incluye el dise\u00f1o y construcci\u00f3n de cinco puentes vehiculares, uno de los cuales se sit\u00faa sobre el r\u00edo Burunga y r\u00edo Mandinga; as\u00ed como excavaciones no clasificadas para cortes y rellenos para la ampliaci\u00f3n de la calzada; control de erosi\u00f3n; rehabilitaci\u00f3n de la estructura de pavimento, adem\u00e1s de cajones pluviales; carril de aceleraci\u00f3n para salida a la carretera Centenario; cunetas pavimentadas tipo trapezoidal; drenajes transversales y sus cabezales de concreto y zampeados; y caj\u00f3n vehicular.<\/p>\n<p>Tambi\u00e9n la v\u00eda, contar\u00e1 con material selecto, capa base, riego de imprimaci\u00f3n, hormig\u00f3n asf\u00e1ltico caliente con metodolog\u00eda Marshall Tipo IV-B.\u00a0 Igualmente, consta en el pliego de cargos que, el Tramo 1 y ramal hacia Burunga, tendr\u00e1 dos carriles de 3.50 m de ancho y hombros de 1.00 m de ancho; mientras que el tramo 2 ser\u00e1 de dos carriles de 3.00 m de ancho y hombros de 0.50 m de ancho; y el carril de salida al Centenario deber\u00e1 tener un carril 3.50 m con hombros de 0.50 m de ancho.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Obras Publicas llev\u00f3 a cabo, \u00a0el jueves, <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/tres-empresas-muestran-interes-por-rehabilitar-via-centenario-nuevo-emperador\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":33642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=33640"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33640\/revisions"}],"predecessor-version":[{"id":33643,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33640\/revisions\/33643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/33642"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=33640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=33640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=33640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}