{"id":33968,"date":"2019-01-04T15:35:26","date_gmt":"2019-01-04T15:35:26","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=33968"},"modified":"2019-01-04T15:35:26","modified_gmt":"2019-01-04T15:35:26","slug":"pn-de-panama-recupero-256-autos-en-2018","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/pn-de-panama-recupero-256-autos-en-2018\/","title":{"rendered":"PN de Panam\u00e1, recuper\u00f3 256 autos en 2018"},"content":{"rendered":"<p>Durante el per\u00edodo del a\u00f1o 2018, unidades de la Polic\u00eda Nacional de la Rep\u00fablica de Panam\u00e1, en asocio con el Ministerio P\u00fablico, llevaron a ejecuci\u00f3n, una serie de operaciones a nivel nacional contra grupos delictivos, entre estos aquellos dedicados a los robos y hurto de veh\u00edculos.<\/p>\n<p>Estas acciones, permitieron recobrar mediante investigaciones de campo, un total de 256 autos que hab\u00edan sido reportados ante las autoridades judiciales. De esta manera, y gracias a los puntos de control establecidos en zonas estrat\u00e9gicas, se consigui\u00f3 ubicar muchos de estos autos, mientras que, otros fueron localizados en poder de organizaciones que operaban entre las provincias de Chiriqu\u00ed, Veraguas, Panam\u00e1 Oeste, Panam\u00e1 y Col\u00f3n.<\/p>\n<p>De esta gesti\u00f3n, al menos 114 personas, fueron capturadas tras su vinculaci\u00f3n a estos grupos delictivos.<\/p>\n<p>Las operaciones denominadas \u2018Bandera e Imperio III\u2019 desarrolladas en los meses de abril y septiembre, propinaron certeros golpes a grupos que operaban desde la Provincia de Panam\u00e1 Oeste hasta sectores en Panam\u00e1 Este, con el robo de autom\u00f3viles, los cuales eran alterados o modificados, para su posterior venta.<\/p>\n<p>Cabe enfatizar, que todos los relacionados a las investigaciones, fueron puestos a \u00f3rdenes del Ministerio P\u00fablico, siguiendo con las acciones operativas en todo el territorio paname\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el per\u00edodo del a\u00f1o 2018, unidades de la Polic\u00eda <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/pn-de-panama-recupero-256-autos-en-2018\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":33970,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=33968"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33968\/revisions"}],"predecessor-version":[{"id":33971,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33968\/revisions\/33971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/33970"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=33968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=33968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=33968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}