{"id":33999,"date":"2019-01-04T19:07:34","date_gmt":"2019-01-04T19:07:34","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=33999"},"modified":"2019-01-04T19:07:34","modified_gmt":"2019-01-04T19:07:34","slug":"puente-sobre-la-quebrada-camazon-presenta-un-13-de-evolucion","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/puente-sobre-la-quebrada-camazon-presenta-un-13-de-evolucion\/","title":{"rendered":"Puente sobre la quebrada Camaz\u00f3n presenta un 13% de evoluci\u00f3n"},"content":{"rendered":"<p>Dentro de la programaci\u00f3n de trabajo del Ministerio de Obras P\u00fablicas se ha conseguido un adelanto del 13% en la construcci\u00f3n del puente sobre la quebrada Camaz\u00f3n, situada en Alanje cabecera, del distrito del mismo nombre en la provincia de Chiriqu\u00ed.<\/p>\n<p>De este modo, personal con equipos del MOP, avanzan en los procesos de desmonte, terraplenado y excavaci\u00f3n a fin de adecuar los niveles del terreno natural a los exigidos para la construcci\u00f3n de los estribos que permitan consolidar las bases del nuevo puente, y as\u00ed pueda contar con el soporte debido para instalar la nueva estructura tipo Mabey, a doble v\u00eda con losa de acero asfaltado.<\/p>\n<p>El director del MOP en Chiriqu\u00ed, Jos\u00e9 An\u00edbal Castillo, recalc\u00f3 que este nuevo puente que se colocar\u00e1 sobre la quebrada Camaz\u00f3n, tiene aproximadamente 98.5 pies de largo y un ancho aproximado de 4 metros y estribos que se construir\u00e1n con una profundidad de 8 metros.<\/p>\n<p>Castillo afirm\u00f3, que esta obra beneficiar\u00e1 a m\u00e1s de 16,500 habitantes del distrito de Alanje, quienes en su mayor\u00eda se dedican a la siembra de ma\u00edz, arroz, frijoles, sorgo, palma aceitera, entre otras actividades. A\u00f1adi\u00f3 adem\u00e1s, que en esta semana, se avanza en labores de construcci\u00f3n de la formaleta de\u00a0refuerzo para el vaciado de estribo derecho, entre otras acciones de relevancia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dentro de la programaci\u00f3n de trabajo del Ministerio de Obras <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/puente-sobre-la-quebrada-camazon-presenta-un-13-de-evolucion\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":34001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=33999"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33999\/revisions"}],"predecessor-version":[{"id":34002,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/33999\/revisions\/34002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/34001"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=33999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=33999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=33999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}