{"id":54050,"date":"2020-06-30T17:46:48","date_gmt":"2020-06-30T17:46:48","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=54050"},"modified":"2020-06-30T17:46:48","modified_gmt":"2020-06-30T17:46:48","slug":"la-ue-autoriza-la-entrada-de-turistas-de-china-con-condiciones-y-de-otros-14-paises","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/la-ue-autoriza-la-entrada-de-turistas-de-china-con-condiciones-y-de-otros-14-paises\/","title":{"rendered":"La UE autoriza la entrada de turistas de China con condiciones y de otros 14 pa\u00edses"},"content":{"rendered":"<p><strong><em>Bruselas (AFP) | <\/em><\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p>Los pa\u00edses de la Uni\u00f3n Europea (UE) dieron este martes su visto bueno a reabrir sus fronteras a partir del 1 de julio a los turistas de una quincena de pa\u00edses, entre ellos China y Uruguay, el \u00fanico latinoamericano.<\/p>\n<p>La lista incluye Argelia, Australia, Canad\u00e1, Georgia, Jap\u00f3n, Montenegro, Marruecos, Nueva Zelanda, Ruanda, Serbia, Corea del Sur, Tailandia, T\u00fanez y Uruguay, as\u00ed como China bajo criterios de reciprocidad, explic\u00f3 el Consejo de la UE.<\/p>\n<p>Los europeos definieron su lista, que se actualizar\u00e1 cada dos semanas, en base a una serie de criterios, entre ellos que la situaci\u00f3n de la pandemia de la COVID-19 en sus territorios sea parecida o mejor a la europea.<\/p>\n<p>La tendencia de rebrotes durante las \u00faltimas dos semanas tambi\u00e9n debe tomarse en cuenta, as\u00ed como la respuesta general a la COVID-19 -pruebas, vigilancia, localizaci\u00f3n de contagios, contenci\u00f3n, tratamiento-.<\/p>\n<p>El acuerdo se trata no obstante de una \u00abrecomendaci\u00f3n\u00bb no vinculante a los pa\u00edses de la UE y a los asociados al espacio de libre circulaci\u00f3n Schengen -Suiza, Liechtenstein, Noruega e Islandia-, responsables de aplicar la decisi\u00f3n.<\/p>\n<p>Adem\u00e1s de estos 15 pa\u00edses, la UE, que se encuentra al inicio de la lucrativa temporada tur\u00edstica, tambi\u00e9n abre sus fronteras a los residentes de Andorra, San Marino, M\u00f3naco y El Vaticano, cuatro peque\u00f1os Estados europeos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bruselas (AFP) | \u00a0 Los pa\u00edses de la Uni\u00f3n Europea <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/la-ue-autoriza-la-entrada-de-turistas-de-china-con-condiciones-y-de-otros-14-paises\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":54051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-54050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/54050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=54050"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/54050\/revisions"}],"predecessor-version":[{"id":54052,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/54050\/revisions\/54052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/54051"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=54050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=54050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=54050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}