{"id":54195,"date":"2020-07-02T20:30:51","date_gmt":"2020-07-02T20:30:51","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=54195"},"modified":"2020-07-02T20:32:41","modified_gmt":"2020-07-02T20:32:41","slug":"parlamento-aleman-apoya-programas-de-compra-de-deuda-del-bce","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/parlamento-aleman-apoya-programas-de-compra-de-deuda-del-bce\/","title":{"rendered":"Parlamento alem\u00e1n apoya programas de compra de deuda del BCE."},"content":{"rendered":"<p><strong><em>Fr\u00e1ncfort (AFP) | <\/em><\/strong><\/p>\n<p>El parlamento alem\u00e1n dio este jueves su apoyo al programa de compra de deuda del Banco Central Europeo (BCE), cuya legalidad hab\u00eda sido puesta en duda por el Tribunal Constitucional del pa\u00eds, poniendo en peligro uno de los pilares de la recuperaci\u00f3n de la zona euro.<\/p>\n<p>Una amplia mayor\u00eda de diputados aprob\u00f3 a mano alzada la moci\u00f3n de apoyo, en respuesta a la inesperada sentencia del alto tribunal el pasado de 5 mayo.<\/p>\n<p>Los jueces del Constitucional hab\u00edan calificado de excesivos e insuficientemente \u00abproporcionales\u00bb los programas de compra de deuda del BCE, que suponen m\u00e1s de 2,6 billones de euros (unos 3,2 billones de d\u00f3lares) desde 2015.<\/p>\n<p>El Tribunal Constitucional alem\u00e1n dio un plazo de tres meses al BCE, as\u00ed como las autoridades alemanas, para que dieran explicaciones y probaran que sus medidas excepcionales se ajustaban a derecho.<\/p>\n<p>En caso contrario, explicaron los jueces, el Banco Central alem\u00e1n deber\u00eda interrumpir su participaci\u00f3n.<\/p>\n<p>\u00abEl inter\u00e9s superior de Alemania es que el futuro de la moneda com\u00fan sea preservado\u00bb, explicaron los diputados en esta moci\u00f3n, apoyada por una gran mayor\u00eda.<\/p>\n<p>Solamente los diputados de extrema derecha y de extrema izquierda se opusieron.<\/p>\n<p>Un miembro del consejo de gobernadores del BCE, Yves Mersch, consider\u00f3 que con esta votaci\u00f3n, \u00abno queda ning\u00fan obst\u00e1culo para que el Bundesbank contin\u00fae con sus compras\u00bb de deuda.<\/p>\n<p>El Tribunal Constitucional considera igualmente el caso \u00abcerrado\u00bb y no se pronunciar\u00e1 a iniciativa propia sobre el tema, una vez todas las respuestas han sido aportadas, explic\u00f3 a la AFP un portavoz.<\/p>\n<p>Sin embargo, la instituci\u00f3n sigue estando obligada legalmente a examinar de nuevo el fondo de la cuesti\u00f3n si recibe una demanda en ese sentido.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fr\u00e1ncfort (AFP) | El parlamento alem\u00e1n dio este jueves su <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/parlamento-aleman-apoya-programas-de-compra-de-deuda-del-bce\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":54196,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-54195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/54195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=54195"}],"version-history":[{"count":2,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/54195\/revisions"}],"predecessor-version":[{"id":54198,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/54195\/revisions\/54198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/54196"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=54195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=54195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=54195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}