{"id":54635,"date":"2020-07-10T17:33:53","date_gmt":"2020-07-10T17:33:53","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=54635"},"modified":"2020-07-10T17:33:53","modified_gmt":"2020-07-10T17:33:53","slug":"diosdado-cabello-presidente-de-la-asamblea-constituyente-tiene-covid-19","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/diosdado-cabello-presidente-de-la-asamblea-constituyente-tiene-covid-19\/","title":{"rendered":"Diosdado Cabello, presidente de la Asamblea Constituyente tiene COVID-19"},"content":{"rendered":"<p>Caracas EFE<br \/>\nEl dirigente oficialista Diosdado Cabello, presidente de la Asamblea Nacional Constituyente (ANC) de Venezuela, dio positivo por coronavirus, seg\u00fan \u00e9l mismo inform\u00f3 a trav\u00e9s de las redes sociales.<\/p>\n<p>\u00abQueridos compa\u00f1eros y compa\u00f1eras, cumplo con informar que luego de realizarme las pruebas correspondientes he resultado positivo en COVID-19, desde ya me encuentro aislado cumpliendo el tratamiento indicado, gracias por sus buenos deseos, con la moral en alto. Nosotros Venceremos\u00bb, indic\u00f3 en su cuenta de Twitter.<\/p>\n<p>El presidente venezolano, Nicol\u00e1s Maduro, redifundi\u00f3 el breve mensaje de Cabello y minutos despu\u00e9s se pronunci\u00f3 al respecto durante un acto gubernamental televisado.<\/p>\n<p>\u00abHa dado positivo Diosdado. Toda mi solidaridad (&#8230;) estoy seguro de que con tu fortaleza moral, espiritual y la protecci\u00f3n de nuestro santo Jos\u00e9 Gregorio Hern\u00e1ndez transitar\u00e1s estos d\u00edas de tratamiento y recuperaci\u00f3n\u00bb, dijo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caracas EFE El dirigente oficialista Diosdado Cabello, presidente de la <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/diosdado-cabello-presidente-de-la-asamblea-constituyente-tiene-covid-19\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":54636,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-54635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/54635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=54635"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/54635\/revisions"}],"predecessor-version":[{"id":54637,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/54635\/revisions\/54637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/54636"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=54635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=54635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=54635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}