{"id":55152,"date":"2020-07-21T19:34:40","date_gmt":"2020-07-21T19:34:40","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=55152"},"modified":"2020-07-21T19:34:40","modified_gmt":"2020-07-21T19:34:40","slug":"vacunas-contra-el-coronavirus-a-precio-de-costo-no-dicen-tres-fabricantes","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/vacunas-contra-el-coronavirus-a-precio-de-costo-no-dicen-tres-fabricantes\/","title":{"rendered":"\u00bfVacunas contra el coronavirus a precio de costo? No, dicen tres fabricantes"},"content":{"rendered":"<p><strong><em>Washington (AFP) | <\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Los laboratorios estadounidenses Pfizer, Merck y Moderna dijeron el martes que, en caso de lograr la vacuna contra el nuevo coronavirus, no la vender\u00e1n a precio de costo, durante una audiencia en el Congreso de Estados Unidos.<\/p>\n<p>Por el contrario, Johnson &amp; Johnson y AstraZeneca se han comprometido a vender inicialmente sus vacunas sin obtener ganancias.<\/p>\n<p>Varias compa\u00f1\u00edas han recibido subvenciones de cientos de millones de d\u00f3lares del gobierno de Estados Unidos u otros pa\u00edses, pero estos acuerdos no siempre vienen con cl\u00e1usulas que limitan el precio m\u00e1ximo de las dosis.<\/p>\n<p>\u00abNo venderemos al costo\u00bb, dijo el presidente de Moderna, Stephen Hoge, en respuesta a una pregunta de un congresista.<\/p>\n<p>Esta compa\u00f1\u00eda de biotecnolog\u00eda ha desarrollado una de las vacunas experimentales m\u00e1s avanzadas, cuyos ensayos de fase 3 comenzar\u00e1n la pr\u00f3xima semana en 30.000 voluntarios.<\/p>\n<p>La empresa recibi\u00f3 483 millones de d\u00f3lares del dinero p\u00fablico de Estados Unidos para financiar la investigaci\u00f3n y el desarrollo, pero sin un contrato de suministro para el pa\u00eds, dijo Hoge.<\/p>\n<p>\u00abNo, no venderemos a precio de costo\u00bb, dijo tambi\u00e9n Julie Gerberding, de Merck, que no tendr\u00e1 ninguna vacuna lista hasta 2021 al menos, y no firm\u00f3 ning\u00fan contrato de suministro con Washington.<\/p>\n<p>\u00abEste es un momento extraordinario y nuestro premio lo reflejar\u00e1\u00bb, agreg\u00f3 John Young, de Pfizer. \u00abDurante la pandemia, fijaremos el precio de nuestra vacuna potencial teniendo en cuenta la actual emergencia sanitaria mundial\u00bb.<\/p>\n<p>Pero AstraZeneca, socio de la Universidad de Oxford en el desarrollo de una de las vacunas m\u00e1s avanzadas en este momento, ya en ensayo de fase 3, firm\u00f3 un contrato por 1.200 millones de d\u00f3lares con la agencia Barda del gobierno de Estados Unidos, que prev\u00e9 la entrega de 300 millones de dosis a precio de costo.<\/p>\n<p>La Uni\u00f3n Europea firm\u00f3 un contrato similar en junio.<\/p>\n<p>Johnson &amp; Johnson, tambi\u00e9n financiado por la llamada operaci\u00f3n \u00abWarp Speed\u00bb de la Casa Blanca (456 millones de d\u00f3lares), dijo por su parte que el precio de m\u00e1s de 1.000 millones de dosis no les dejar\u00eda ganancias durante la fase de emergencia de la pandemia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington (AFP) | &nbsp; Los laboratorios estadounidenses Pfizer, Merck y <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/vacunas-contra-el-coronavirus-a-precio-de-costo-no-dicen-tres-fabricantes\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":55153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-55152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/55152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=55152"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/55152\/revisions"}],"predecessor-version":[{"id":55154,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/55152\/revisions\/55154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/55153"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=55152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=55152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=55152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}