{"id":55313,"date":"2020-07-23T19:33:20","date_gmt":"2020-07-23T19:33:20","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=55313"},"modified":"2020-07-23T19:33:20","modified_gmt":"2020-07-23T19:33:20","slug":"camara-baja-aprueba-proyecto-contra-el-veto-migratorio-de-donald-trump","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/camara-baja-aprueba-proyecto-contra-el-veto-migratorio-de-donald-trump\/","title":{"rendered":"C\u00e1mara Baja aprueba proyecto contra el veto migratorio de Donald Trump"},"content":{"rendered":"<p><strong><em>Washington EFE<\/em><\/strong><\/p>\n<p>La C\u00e1mara de Representantes de EE.UU., controlada por la oposici\u00f3n dem\u00f3crata, aprob\u00f3 un proyecto de ley que busca revocar el veto migratorio del presidente Donald Trump contra refugiados y ciudadanos de pa\u00edses de mayor\u00eda musulmana y espera restringir la capacidad del Ejecutivo para imponer este tipo de medidas.<\/p>\n<p>La iniciativa, presentada por la congresista Judy Chu y denominada Ley Nacional contra la Discriminaci\u00f3n basada en el Origen para los No Inmigrantes (NO BAN, en ingl\u00e9s), logr\u00f3 una votaci\u00f3n favorable 233-183.<\/p>\n<p>Sin embargo, para convertirse en ley deber\u00e1 lograr el aval del Senado, dominado por el Partido Republicano, y ser firmada posteriormente por el presidente Trump.<\/p>\n<p>El proyecto propone acabar con el veto actual e impedir que la Administraci\u00f3n de Trump introduzca nuevas restricciones sin presentar ninguna justificaci\u00f3n y sin consultarlo con el Congreso, adem\u00e1s de que plantea prohibir la discriminaci\u00f3n religiosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington EFE La C\u00e1mara de Representantes de EE.UU., controlada por <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/camara-baja-aprueba-proyecto-contra-el-veto-migratorio-de-donald-trump\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":55314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-55313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/55313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=55313"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/55313\/revisions"}],"predecessor-version":[{"id":55315,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/55313\/revisions\/55315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/55314"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=55313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=55313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=55313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}