{"id":5599,"date":"2015-06-04T14:23:46","date_gmt":"2015-06-04T14:23:46","guid":{"rendered":""},"modified":"2015-06-04T14:23:46","modified_gmt":"2015-06-04T14:23:46","slug":"una-nueva-opcion-para-la-comunicacion-canal-tv-en-senal-digital","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/una-nueva-opcion-para-la-comunicacion-canal-tv-en-senal-digital\/","title":{"rendered":"Una nueva opci\u00f3n para la comunicaci\u00f3n \u201cCANAL TV\u201d en se\u00f1al digital"},"content":{"rendered":"<p>\nRecientemente el Canal de Panam\u00e1 lanz\u00f3 de manera oficial  tu CANAL TV , la se\u00f1al de televisi\u00f3n abierta que establece un nuevo puente de comunicaci\u00f3n entre la v\u00eda acu\u00e1tica y la comunidad. <\/p>\n<p>Desde el mi\u00e9rcoles 3 de junio  tu CANAL TV , comenz\u00f3 a emitir su se\u00f1al en el canal 26 de televisi\u00f3n digital abierta, con cobertura en las provincias de Panam\u00e1, Panam\u00e1 Oeste y Col\u00f3n. <\/p>\n<p>&ldquo;Queremos mantenerlos informados, abrir una ventana a la educaci\u00f3n y la cultura, que conozcan lo que hacemos por el desarrollo sostenible del ambiente, la preservaci\u00f3n de nuestra historia, el arte, la cultura y nuestra gente&rdquo;, manifest\u00f3 el administrador del Canal, Jorge L. Quijano, al hacer el lanzamiento en una ceremonia en el Centro de Visitantes de Miraflores (CVM). <\/p>\n<p>A\u00f1adi\u00f3 que la idea es vivir juntos cada momento de esta gran haza\u00f1a que conduce a Panam\u00e1 al futuro, que es el Canal Ampliado. Para ello, recalc\u00f3 Quijano, se cuenta con la \u00faltima tecnolog\u00eda y un equipo de profesionales de la producci\u00f3n y la comunicaci\u00f3n social. <\/p>\n<p> Es importante resaltar, que desde ahora  , Tu CANAL TV  tambi\u00e9n est\u00e1 disponible en el Canal 26 de +TV Digital post-pago de Cable &#038; Wireless Panam\u00e1, y en fecha pr\u00f3xima se incluir\u00e1 en otros sistemas de Cable. <\/p>\n<p>Adem\u00e1s transmite de forma continua 24 horas, los siete d\u00edas de la semana, en se\u00f1al digital de alta definici\u00f3n, con una variada parrilla rotativa, la cual incluye: <\/p>\n<p> La cuenca y su Gente:  un acercamiento a las comunidades de la cuenca hidrogr\u00e1fica del Canal de Panam\u00e1, para escuchar y sentir a sus moradores. <\/p>\n<p> De Visita en el Canal:  acompa\u00f1a a reconocidas figuras del quehacer nacional, que nos cuentan sus experiencias de vida en un recorrido por esta maravilla de la ingenier\u00eda mundial. <\/p>\n<p> Conversando con&hellip;:  las personalidades m\u00e1s influyentes del pa\u00eds relatan su trayectoria y vivencias en este nuevo programa. <\/p>\n<p> Documentales:  si quieres conocer a profundidad temas de inter\u00e9s, historia, ciencia, tecnolog\u00eda, arte y cultura. <\/p>\n<p> El Canal Por Dentro:  para conocer los diversos programas que se ejecutan dentro del Canal de Panam\u00e1 para un desarrollo integral y sostenible, tienes que conocer el Canal Por Dentro. Modernizaci\u00f3n. Innovaci\u00f3n y Conectividad. <\/p>\n<p> Tu Canal al D\u00eda:  reportajes, noticias de actualidad y el d\u00eda a d\u00eda en esta maravilla de la ingenier\u00eda moderna&hellip; Arte, Cultura y Musicales. <\/p>\n<p>Cabe mencionar, que tu  CANAL TV  transmitir\u00e1 en vivo cada uno de los hitos en las obras del Canal Ampliado y los eventos de la v\u00eda acu\u00e1tica que revisten importancia nacional, para que se observen de primera mano. <\/p>\n<p>Otra manera de comunicarse es a trav\u00e9s del Twitter  @canaldepanama  y en Facebook  http:\/\/facebook.com\/tucanaltvpanama  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recientemente el Canal de Panam\u00e1 lanz\u00f3 de manera oficial tu <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/una-nueva-opcion-para-la-comunicacion-canal-tv-en-senal-digital\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":5600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/5599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=5599"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/5599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/5600"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=5599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=5599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=5599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}