{"id":5679,"date":"2015-06-09T15:04:30","date_gmt":"2015-06-09T15:04:30","guid":{"rendered":""},"modified":"2015-06-09T15:04:30","modified_gmt":"2015-06-09T15:04:30","slug":"inauguran-sede-regional-del-meduca-en-panama-norte","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/inauguran-sede-regional-del-meduca-en-panama-norte\/","title":{"rendered":"Inauguran sede regional del MEDUCA, en Panam\u00e1 Norte"},"content":{"rendered":"<p>\nLas autoridades del Ministerio de Educaci\u00f3n (MEDUCA) inauguraron este recientemente la Direcci\u00f3n Regional de Panam\u00e1 Norte, situada en las instalaciones de la escuela Rep\u00fablica de Egipto, en el corregimiento de Las Cumbres. <\/p>\n<p>Dicha oficina se convirti\u00f3 en la n\u00famero 16 de esta entidad. La misma, estar\u00e1 a cargo de Manuel Caballero, quien ser\u00e1 su Director, y la Subdirectora administrativa, ser\u00e1 Yulissa Bernal. <\/p>\n<p>Cabe resaltar, que esta nueva regional de Educaci\u00f3n tiene bajo su paraguas 39 escuelas p\u00fablicas. <\/p>\n<p>Ciertamente, el MEDUCA, est\u00e1 en el proceso de elegir a los otros 15 directores. <\/p>\n<p>Sobre el particular, la ministra Marcela Paredes, junto a Irving Halman, director de la Autoridad Nacional para la Innovaci\u00f3n Gubernamental (AIG), lanz\u00f3 en ese centro escolar la nueva aplicaci\u00f3n &ldquo;Ubica tu escuela primero&rdquo;, que permitir\u00e1 localizar geogr\u00e1ficamente los planteles educativos sobre el mapa de Panam\u00e1. <\/p>\n<p>De igual manera, Halman manifest\u00f3 que, por el momento, la herramienta tecnol\u00f3gica puede ser descargada en tel\u00e9fonos m\u00f3viles, pero que se trabaja para lograrlo en otros equipos como tabletas. <\/p>\n<p>A su vez, Paredes declar\u00f3 que la segunda fase de la plataforma mostrar\u00e1 informaci\u00f3n de la oferta acad\u00e9mica, nombre del director, los subdirectores, supervisores, entre otros aspectos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las autoridades del Ministerio de Educaci\u00f3n (MEDUCA) inauguraron este recientemente <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/inauguran-sede-regional-del-meduca-en-panama-norte\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":5680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/5679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=5679"}],"version-history":[{"count":0,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/5679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/5680"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=5679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=5679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=5679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}