{"id":89371,"date":"2022-11-10T17:36:49","date_gmt":"2022-11-10T17:36:49","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=89371"},"modified":"2022-11-10T17:36:49","modified_gmt":"2022-11-10T17:36:49","slug":"policia-rescata-a-3-menores-de-edad-en-la-desembocadura-del-rio-teta-en-el-distrito-de-chame","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/policia-rescata-a-3-menores-de-edad-en-la-desembocadura-del-rio-teta-en-el-distrito-de-chame\/","title":{"rendered":"Polic\u00eda rescata a 3 menores de edad en la desembocadura del R\u00edo Teta, en el distrito de Chame"},"content":{"rendered":"<p>Unidades policiales que se manten\u00edan en recorrido preventivo en \u00e1reas de playas y balnearios, logran rescatar sanos y salvos a tres menores de edad, quienes quedaron atrapados e incomunicados al otro extremo del r\u00edo Teta, ubicado en la playa Punta Barco Viejo.<\/p>\n<p>El rescate, se logra cuando uno de los familiares de los menores, se asusta al ver que una cabeza de agua viene bajando y provoca la crecida del r\u00edo, por lo que marcan al 104 inmediatamente, la alerta es recibida en sala de Atenci\u00f3n Ciudadana de la Polic\u00eda Nacional en San Carlos.<\/p>\n<p>Los menores, que se encontraban del otro lado del r\u00edo cerca a la Playa, fueron auxiliados por las unidades quienes recibieron el apoyo de la comunidad para poder cruzar la corriente en bote.<\/p>\n<p>El subcomisionado Vasco Rodr\u00edguez, se\u00f1al\u00f3 que, afortunadamente el trabajo en equipo entre la Polic\u00eda y la comunidad, ayud\u00f3 al rescate de estos menores, quienes agradecieron el apoyo brindado.<\/p>\n<p>La Polic\u00eda Nacional cumple con su deber de Proteger y Servir acudiendo al llamado de la ciudadan\u00eda ante los diversos eventos.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: PNP<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unidades policiales que se manten\u00edan en recorrido preventivo en \u00e1reas <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/policia-rescata-a-3-menores-de-edad-en-la-desembocadura-del-rio-teta-en-el-distrito-de-chame\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":89372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-89371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/89371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=89371"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/89371\/revisions"}],"predecessor-version":[{"id":89376,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/89371\/revisions\/89376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/89372"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=89371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=89371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=89371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}