{"id":94997,"date":"2024-04-09T09:45:41","date_gmt":"2024-04-09T14:45:41","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=94997"},"modified":"2024-04-09T09:45:41","modified_gmt":"2024-04-09T14:45:41","slug":"en-changuinola-dictan-docencia-sobre-el-autismo-y-la-importancia-de-la-fisioterapia-a-padres-de-familias","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/en-changuinola-dictan-docencia-sobre-el-autismo-y-la-importancia-de-la-fisioterapia-a-padres-de-familias\/","title":{"rendered":"En Changuinola dictan docencia sobre el Autismo y la Importancia de la Fisioterapia a padres de familias"},"content":{"rendered":"<p><strong><em>Como parte de las actividades conmemorativas del mes de la \u201cConcienciaci\u00f3n del Autismo\u201d, el Departamento de Fisioterapia, a trav\u00e9s de sus especialistas asignados a la Extensi\u00f3n de Bocas del Toro, realizaron una \u201cDocencia sobre el Autismo y la Importancia de la Fisioterapia\u201d, dirigida a los padres de familias, que se imparti\u00f3 en el MINSA Capsi de Finca Las 30, en la ciudad de Changuinola, provincia de Bocas del Toro.\u00a0<\/em><\/strong><\/p>\n<p><strong><em>El objetivo principal fue promover una mayor comprensi\u00f3n sobre el autismo y resaltar el rol de la fisioterapia que busca mejorar la calidad de vida de las personas con este trastorno del neurodesarrollo.\u00a0<\/em><\/strong><\/p>\n<p><strong><em>La licenciada Stephanie Gonz\u00e1lez, fisioterapeuta en la Extensi\u00f3n de Bocas del Toro, enfatiz\u00f3 sobre la necesidad de eliminar estigmas y mitos, as\u00ed como fomentar la inclusi\u00f3n a trav\u00e9s de enfoques terap\u00e9uticos especializados que potencian el entendimiento y respeto hacia las necesidades y fortalezas individuales.<\/em><\/strong><\/p>\n<p><strong><em>\u201cLa concienciaci\u00f3n sobre el autismo y la relevancia de la fisioterapia son pilares fundamentales para elevar la calidad de vida de las personas con este trastorno, al mismo tiempo que se busca promover la inclusi\u00f3n y el respeto hacia ellos. La fisioterapia desempe\u00f1a un rol esencial en abordar las dificultades motoras y sensoriales, facilitando el desarrollo de habilidades y promoviendo la independencia\u201d, explic\u00f3 la licenciada Gonz\u00e1lez. \u00a0<\/em><\/strong><\/p>\n<p><strong><em>Los beneficios de la fisioterapia incluyen mejoras en la coordinaci\u00f3n, equilibrio, fuerza muscular y motricidad, facilitando la independencia y la realizaci\u00f3n de actividades diarias.\u00a0<\/em><\/strong><\/p>\n<p><strong><em>Adem\u00e1s, los ejercicios pueden contribuir a reducir la ansiedad, mejorar la regulaci\u00f3n emocional y promover un estilo de vida activo y saludable. Los fisioterapeutas colaboran estrechamente con otros profesionales, como terapeutas ocupacionales y fonoaudi\u00f3logos, para ofrecer un enfoque integral y personalizado que beneficie a las personas con autismo.<\/em><\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p>Fuente: IPHE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de las actividades conmemorativas del mes de la <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/en-changuinola-dictan-docencia-sobre-el-autismo-y-la-importancia-de-la-fisioterapia-a-padres-de-familias\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":94998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-94997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/94997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=94997"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/94997\/revisions"}],"predecessor-version":[{"id":94999,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/94997\/revisions\/94999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/94998"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=94997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=94997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=94997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}