{"id":95703,"date":"2024-05-10T10:59:14","date_gmt":"2024-05-10T15:59:14","guid":{"rendered":"https:\/\/sertv.gob.pa\/nacionalfm\/?p=95703"},"modified":"2024-05-10T10:59:14","modified_gmt":"2024-05-10T15:59:14","slug":"a-traves-de-atencion-al-asegurado-personal-en-chiriqui-se-capacita-en-cursos-de-lenguaje-de-senas","status":"publish","type":"post","link":"https:\/\/sertv.gob.pa\/nacionalfm\/a-traves-de-atencion-al-asegurado-personal-en-chiriqui-se-capacita-en-cursos-de-lenguaje-de-senas\/","title":{"rendered":"A Trav\u00e9s de Atenci\u00f3n al Asegurado, personal en Chiriqu\u00ed se capacita en cursos de lenguaje de se\u00f1as"},"content":{"rendered":"<p><strong><em>La Oficina\u00a0 de Equiparaci\u00f3n de Oportunidades de la Caja de Seguro Social (CSS), imparti\u00f3 capacitaci\u00f3n a m\u00e1s de 20 funcionarios sobre lenguaje de se\u00f1as a personal administrativo de las diferentes unidades ejecutoras en la provincia de Chiriqu\u00ed.<\/em><\/strong><\/p>\n<p><strong><em>La licenciada Aixa Mart\u00ednez, coordinadora regional de Chiriqu\u00ed y Bocas del Toro, dijo: \u00abEstas capacitaciones van dirigidas a personal de diferentes servicios, como: laboratorio, farmacia, atenci\u00f3n al asegurado y personal administrativo de la Caja de Seguro Social, impartidas por especialistas en el tema\u00bb.<\/em><\/strong><\/p>\n<p><strong><em>Este tipo de capacitaci\u00f3n es importante para apoyar a la poblaci\u00f3n sorda que acude por los servicios que se brinda en las diferentes unidades ejecutoras; adem\u00e1s de mejorar la calidad de atenci\u00f3n, con un servicio inclusivo, recordando que, la Caja de Seguro Social, esta para servirles.<\/em><\/strong><\/p>\n<p><strong><em>Estos cursos brindan la oportunidad, tanto a los colaboradores como a los pacientes que tienen alguna deficiencia auditiva, de poder comunicarse al momento de solicitar un servicio.<\/em><\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p>Fuente: CSS<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Oficina\u00a0 de Equiparaci\u00f3n de Oportunidades de la Caja de <a href=\"https:\/\/sertv.gob.pa\/nacionalfm\/a-traves-de-atencion-al-asegurado-personal-en-chiriqui-se-capacita-en-cursos-de-lenguaje-de-senas\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":9,"featured_media":95704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-95703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"_links":{"self":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/95703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/comments?post=95703"}],"version-history":[{"count":1,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/95703\/revisions"}],"predecessor-version":[{"id":95705,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/posts\/95703\/revisions\/95705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media\/95704"}],"wp:attachment":[{"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/media?parent=95703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/categories?post=95703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertv.gob.pa\/nacionalfm\/wp-json\/wp\/v2\/tags?post=95703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}